{"id":13608,"date":"2018-08-10T17:46:22","date_gmt":"2018-08-10T20:46:22","guid":{"rendered":"https:\/\/federasbackup.meltcomunicacao.com.br\/?p=13608"},"modified":"2018-08-10T17:46:22","modified_gmt":"2018-08-10T20:46:22","slug":"hospital-marcio-cunha-recebe-as-vitimas-da-explosao-na-usiminas","status":"publish","type":"post","link":"https:\/\/www.federassantas.org.br\/novosite\/hospital-marcio-cunha-recebe-as-vitimas-da-explosao-na-usiminas\/","title":{"rendered":"Hospital M\u00e1rcio Cunha recebe as v\u00edtimas da explos\u00e3o na Usiminas"},"content":{"rendered":"<div class=\"mc-column content-text active-extra-styles \" data-block-type=\"unstyled\" data-block-weight=\"44\" data-block-id=\"14\">\n<p class=\"content-text__container \" style=\"text-align: justify;\" data-track-category=\"Link no Texto\" data-track-links=\"\">Uma explos\u00e3o dentro da\u00a0Usiminas, em\u00a0Ipatinga, fez a usina ser evacuada na tarde desta sexta-feira (10). Trinta pessoas foram levadas para o hospital M\u00e1rcio Cunha, n\u00e3o h\u00e1 feridos em estado grave e a maior parte das pessoas apresentam leves escoria\u00e7\u00f5es.<\/p>\n<\/div>\n<div class=\"mc-column content-text active-extra-styles \" data-block-type=\"unstyled\" data-block-weight=\"37\" data-block-id=\"15\">\n<p class=\"content-text__container \" style=\"text-align: justify;\" data-track-category=\"Link no Texto\" data-track-links=\"\">&#8220;Todas essas v\u00edtimas prestavam servi\u00e7o ou eram funcion\u00e1rios da empresa. Um fator que favoreceu a menor gravidade da ocorr\u00eancia foi o fato da f\u00e1brica estar em hor\u00e1rio de almo\u00e7o no momento da explos\u00e3o&#8221;, afirma nota da corpora\u00e7\u00e3o.<\/p>\n<p data-track-category=\"Link no Texto\" data-track-links=\"\"><img fetchpriority=\"high\" decoding=\"async\" class=\"wp-image-13610 alignleft\" src=\"http:\/\/federasbackup.meltcomunicacao.com.br\/wp-content\/uploads\/2018\/08\/fup20180810325-1-300x200.jpg\" alt=\"\" width=\"401\" height=\"267\" srcset=\"https:\/\/www.federassantas.org.br\/novosite\/wp-content\/uploads\/2018\/08\/fup20180810325-1-300x200.jpg 300w, https:\/\/www.federassantas.org.br\/novosite\/wp-content\/uploads\/2018\/08\/fup20180810325-1-768x512.jpg 768w, https:\/\/www.federassantas.org.br\/novosite\/wp-content\/uploads\/2018\/08\/fup20180810325-1.jpg 1000w\" sizes=\"(max-width: 401px) 100vw, 401px\" \/><\/p>\n<p style=\"text-align: justify;\" data-track-category=\"Link no Texto\" data-track-links=\"\">O acidente ocorreu em um dos gas\u00f4metros, na \u00e1rea da aciaria, onde o ferro \u00e9 convertido em a\u00e7o. N\u00e3o se sabe ainda a causa da explos\u00e3o. O governo de MG informou que a f\u00e1brica est\u00e1 fechada, e as atividades no local somente ser\u00e3o retomadas ap\u00f3s libera\u00e7\u00e3o pelo Corpo de Bombeiros.<\/p>\n<p style=\"text-align: justify;\" data-track-category=\"Link no Texto\" data-track-links=\"\">Saiba mais em:\u00a0<a href=\"https:\/\/g1.globo.com\/mg\/vales-mg\/noticia\/2018\/08\/10\/explosao-e-registrada-na-usiminas-e-usina-e-evacuada-em-ipatinga.ghtml\">https:\/\/g1.globo.com\/mg\/vales-mg\/noticia\/2018\/08\/10\/explosao-e-registrada-na-usiminas-e-usina-e-evacuada-em-ipatinga.ghtml<\/a><\/p>\n<p style=\"text-align: justify;\" data-track-category=\"Link no Texto\" data-track-links=\"\">Fonte: <a href=\"https:\/\/g1.globo.com\/\">G1<\/a><\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Uma explos\u00e3o dentro da\u00a0Usiminas, em\u00a0Ipatinga, fez a usina ser evacuada na tarde desta sexta-feira (10). Trinta pessoas foram levadas para o hospital M\u00e1rcio Cunha, n\u00e3o h\u00e1 feridos em estado grave e a maior parte das pessoas apresentam leves escoria\u00e7\u00f5es. &#8220;Todas essas v\u00edtimas prestavam servi\u00e7o ou eram funcion\u00e1rios da empresa. Um fator que favoreceu a menor [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":13611,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[140,139],"tags":[],"class_list":["post-13608","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias","category-noticias-filiados"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Hospital M\u00e1rcio Cunha recebe as v\u00edtimas da explos\u00e3o na Usiminas - Federassantas<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.federassantas.org.br\/novosite\/hospital-marcio-cunha-recebe-as-vitimas-da-explosao-na-usiminas\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Hospital M\u00e1rcio Cunha recebe as v\u00edtimas da explos\u00e3o na Usiminas - Federassantas\" \/>\n<meta property=\"og:description\" content=\"Uma explos\u00e3o dentro da\u00a0Usiminas, em\u00a0Ipatinga, fez a usina ser evacuada na tarde desta sexta-feira (10). Trinta pessoas foram levadas para o hospital M\u00e1rcio Cunha, n\u00e3o h\u00e1 feridos em estado grave e a maior parte das pessoas apresentam leves escoria\u00e7\u00f5es. &#8220;Todas essas v\u00edtimas prestavam servi\u00e7o ou eram funcion\u00e1rios da empresa. Um fator que favoreceu a menor [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.federassantas.org.br\/novosite\/hospital-marcio-cunha-recebe-as-vitimas-da-explosao-na-usiminas\/\" \/>\n<meta property=\"og:site_name\" content=\"Federassantas\" \/>\n<meta property=\"article:published_time\" content=\"2018-08-10T20:46:22+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.federassantas.org.br\/novosite\/wp-content\/uploads\/2018\/08\/marcio-cunha-1-1024x512-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"512\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"admin-federas\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin-federas\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.federassantas.org.br\/novosite\/hospital-marcio-cunha-recebe-as-vitimas-da-explosao-na-usiminas\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.federassantas.org.br\/novosite\/hospital-marcio-cunha-recebe-as-vitimas-da-explosao-na-usiminas\/\"},\"author\":{\"name\":\"admin-federas\",\"@id\":\"https:\/\/www.federassantas.org.br\/novosite\/#\/schema\/person\/75fed98158349313fe56175f232f513c\"},\"headline\":\"Hospital M\u00e1rcio Cunha recebe as v\u00edtimas da explos\u00e3o na Usiminas\",\"datePublished\":\"2018-08-10T20:46:22+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.federassantas.org.br\/novosite\/hospital-marcio-cunha-recebe-as-vitimas-da-explosao-na-usiminas\/\"},\"wordCount\":174,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/www.federassantas.org.br\/novosite\/#organization\"},\"image\":{\"@id\":\"https:\/\/www.federassantas.org.br\/novosite\/hospital-marcio-cunha-recebe-as-vitimas-da-explosao-na-usiminas\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.federassantas.org.br\/novosite\/wp-content\/uploads\/2018\/08\/marcio-cunha-1-1024x512-1.jpg\",\"articleSection\":[\"Not\u00edcias\",\"Not\u00edcias filiados\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/www.federassantas.org.br\/novosite\/hospital-marcio-cunha-recebe-as-vitimas-da-explosao-na-usiminas\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.federassantas.org.br\/novosite\/hospital-marcio-cunha-recebe-as-vitimas-da-explosao-na-usiminas\/\",\"url\":\"https:\/\/www.federassantas.org.br\/novosite\/hospital-marcio-cunha-recebe-as-vitimas-da-explosao-na-usiminas\/\",\"name\":\"Hospital M\u00e1rcio Cunha recebe as v\u00edtimas da explos\u00e3o na Usiminas - Federassantas\",\"isPartOf\":{\"@id\":\"https:\/\/www.federassantas.org.br\/novosite\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.federassantas.org.br\/novosite\/hospital-marcio-cunha-recebe-as-vitimas-da-explosao-na-usiminas\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.federassantas.org.br\/novosite\/hospital-marcio-cunha-recebe-as-vitimas-da-explosao-na-usiminas\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.federassantas.org.br\/novosite\/wp-content\/uploads\/2018\/08\/marcio-cunha-1-1024x512-1.jpg\",\"datePublished\":\"2018-08-10T20:46:22+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.federassantas.org.br\/novosite\/hospital-marcio-cunha-recebe-as-vitimas-da-explosao-na-usiminas\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.federassantas.org.br\/novosite\/hospital-marcio-cunha-recebe-as-vitimas-da-explosao-na-usiminas\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.federassantas.org.br\/novosite\/hospital-marcio-cunha-recebe-as-vitimas-da-explosao-na-usiminas\/#primaryimage\",\"url\":\"https:\/\/www.federassantas.org.br\/novosite\/wp-content\/uploads\/2018\/08\/marcio-cunha-1-1024x512-1.jpg\",\"contentUrl\":\"https:\/\/www.federassantas.org.br\/novosite\/wp-content\/uploads\/2018\/08\/marcio-cunha-1-1024x512-1.jpg\",\"width\":1024,\"height\":512},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.federassantas.org.br\/novosite\/hospital-marcio-cunha-recebe-as-vitimas-da-explosao-na-usiminas\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/www.federassantas.org.br\/novosite\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Hospital M\u00e1rcio Cunha recebe as v\u00edtimas da explos\u00e3o na Usiminas\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.federassantas.org.br\/novosite\/#website\",\"url\":\"https:\/\/www.federassantas.org.br\/novosite\/\",\"name\":\"Federassantas\",\"description\":\"Entidade de representa\u00e7\u00e3o e fortalecimento das Santas Casas, hospitais filantr\u00f3picos e entidades beneficentes de sa\u00fade de Minas Gerais, atuando na defesa institucional, qualifica\u00e7\u00e3o da gest\u00e3o e sustentabilidade do setor.\",\"publisher\":{\"@id\":\"https:\/\/www.federassantas.org.br\/novosite\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.federassantas.org.br\/novosite\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.federassantas.org.br\/novosite\/#organization\",\"name\":\"Federassantas\",\"url\":\"https:\/\/www.federassantas.org.br\/novosite\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.federassantas.org.br\/novosite\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.federassantas.org.br\/novosite\/wp-content\/uploads\/2021\/12\/logo.png\",\"contentUrl\":\"https:\/\/www.federassantas.org.br\/novosite\/wp-content\/uploads\/2021\/12\/logo.png\",\"width\":243,\"height\":59,\"caption\":\"Federassantas\"},\"image\":{\"@id\":\"https:\/\/www.federassantas.org.br\/novosite\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.federassantas.org.br\/novosite\/#\/schema\/person\/75fed98158349313fe56175f232f513c\",\"name\":\"admin-federas\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.federassantas.org.br\/novosite\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/2a02d7dda59fe8dc6b7ffd3f652e2efede5ccf0dd89dfdc8137c5517f3de8407?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/2a02d7dda59fe8dc6b7ffd3f652e2efede5ccf0dd89dfdc8137c5517f3de8407?s=96&d=mm&r=g\",\"caption\":\"admin-federas\"},\"sameAs\":[\"https:\/\/www.federassantas.org.br\/novosite\/\"],\"url\":\"https:\/\/www.federassantas.org.br\/novosite\/author\/admin-federas\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Hospital M\u00e1rcio Cunha recebe as v\u00edtimas da explos\u00e3o na Usiminas - Federassantas","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.federassantas.org.br\/novosite\/hospital-marcio-cunha-recebe-as-vitimas-da-explosao-na-usiminas\/","og_locale":"pt_BR","og_type":"article","og_title":"Hospital M\u00e1rcio Cunha recebe as v\u00edtimas da explos\u00e3o na Usiminas - Federassantas","og_description":"Uma explos\u00e3o dentro da\u00a0Usiminas, em\u00a0Ipatinga, fez a usina ser evacuada na tarde desta sexta-feira (10). Trinta pessoas foram levadas para o hospital M\u00e1rcio Cunha, n\u00e3o h\u00e1 feridos em estado grave e a maior parte das pessoas apresentam leves escoria\u00e7\u00f5es. &#8220;Todas essas v\u00edtimas prestavam servi\u00e7o ou eram funcion\u00e1rios da empresa. Um fator que favoreceu a menor [&hellip;]","og_url":"https:\/\/www.federassantas.org.br\/novosite\/hospital-marcio-cunha-recebe-as-vitimas-da-explosao-na-usiminas\/","og_site_name":"Federassantas","article_published_time":"2018-08-10T20:46:22+00:00","og_image":[{"width":1024,"height":512,"url":"https:\/\/www.federassantas.org.br\/novosite\/wp-content\/uploads\/2018\/08\/marcio-cunha-1-1024x512-1.jpg","type":"image\/jpeg"}],"author":"admin-federas","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"admin-federas","Est. tempo de leitura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.federassantas.org.br\/novosite\/hospital-marcio-cunha-recebe-as-vitimas-da-explosao-na-usiminas\/#article","isPartOf":{"@id":"https:\/\/www.federassantas.org.br\/novosite\/hospital-marcio-cunha-recebe-as-vitimas-da-explosao-na-usiminas\/"},"author":{"name":"admin-federas","@id":"https:\/\/www.federassantas.org.br\/novosite\/#\/schema\/person\/75fed98158349313fe56175f232f513c"},"headline":"Hospital M\u00e1rcio Cunha recebe as v\u00edtimas da explos\u00e3o na Usiminas","datePublished":"2018-08-10T20:46:22+00:00","mainEntityOfPage":{"@id":"https:\/\/www.federassantas.org.br\/novosite\/hospital-marcio-cunha-recebe-as-vitimas-da-explosao-na-usiminas\/"},"wordCount":174,"commentCount":0,"publisher":{"@id":"https:\/\/www.federassantas.org.br\/novosite\/#organization"},"image":{"@id":"https:\/\/www.federassantas.org.br\/novosite\/hospital-marcio-cunha-recebe-as-vitimas-da-explosao-na-usiminas\/#primaryimage"},"thumbnailUrl":"https:\/\/www.federassantas.org.br\/novosite\/wp-content\/uploads\/2018\/08\/marcio-cunha-1-1024x512-1.jpg","articleSection":["Not\u00edcias","Not\u00edcias filiados"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.federassantas.org.br\/novosite\/hospital-marcio-cunha-recebe-as-vitimas-da-explosao-na-usiminas\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.federassantas.org.br\/novosite\/hospital-marcio-cunha-recebe-as-vitimas-da-explosao-na-usiminas\/","url":"https:\/\/www.federassantas.org.br\/novosite\/hospital-marcio-cunha-recebe-as-vitimas-da-explosao-na-usiminas\/","name":"Hospital M\u00e1rcio Cunha recebe as v\u00edtimas da explos\u00e3o na Usiminas - Federassantas","isPartOf":{"@id":"https:\/\/www.federassantas.org.br\/novosite\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.federassantas.org.br\/novosite\/hospital-marcio-cunha-recebe-as-vitimas-da-explosao-na-usiminas\/#primaryimage"},"image":{"@id":"https:\/\/www.federassantas.org.br\/novosite\/hospital-marcio-cunha-recebe-as-vitimas-da-explosao-na-usiminas\/#primaryimage"},"thumbnailUrl":"https:\/\/www.federassantas.org.br\/novosite\/wp-content\/uploads\/2018\/08\/marcio-cunha-1-1024x512-1.jpg","datePublished":"2018-08-10T20:46:22+00:00","breadcrumb":{"@id":"https:\/\/www.federassantas.org.br\/novosite\/hospital-marcio-cunha-recebe-as-vitimas-da-explosao-na-usiminas\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.federassantas.org.br\/novosite\/hospital-marcio-cunha-recebe-as-vitimas-da-explosao-na-usiminas\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.federassantas.org.br\/novosite\/hospital-marcio-cunha-recebe-as-vitimas-da-explosao-na-usiminas\/#primaryimage","url":"https:\/\/www.federassantas.org.br\/novosite\/wp-content\/uploads\/2018\/08\/marcio-cunha-1-1024x512-1.jpg","contentUrl":"https:\/\/www.federassantas.org.br\/novosite\/wp-content\/uploads\/2018\/08\/marcio-cunha-1-1024x512-1.jpg","width":1024,"height":512},{"@type":"BreadcrumbList","@id":"https:\/\/www.federassantas.org.br\/novosite\/hospital-marcio-cunha-recebe-as-vitimas-da-explosao-na-usiminas\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/www.federassantas.org.br\/novosite\/"},{"@type":"ListItem","position":2,"name":"Hospital M\u00e1rcio Cunha recebe as v\u00edtimas da explos\u00e3o na Usiminas"}]},{"@type":"WebSite","@id":"https:\/\/www.federassantas.org.br\/novosite\/#website","url":"https:\/\/www.federassantas.org.br\/novosite\/","name":"Federassantas","description":"Entidade de representa\u00e7\u00e3o e fortalecimento das Santas Casas, hospitais filantr\u00f3picos e entidades beneficentes de sa\u00fade de Minas Gerais, atuando na defesa institucional, qualifica\u00e7\u00e3o da gest\u00e3o e sustentabilidade do setor.","publisher":{"@id":"https:\/\/www.federassantas.org.br\/novosite\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.federassantas.org.br\/novosite\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/www.federassantas.org.br\/novosite\/#organization","name":"Federassantas","url":"https:\/\/www.federassantas.org.br\/novosite\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.federassantas.org.br\/novosite\/#\/schema\/logo\/image\/","url":"https:\/\/www.federassantas.org.br\/novosite\/wp-content\/uploads\/2021\/12\/logo.png","contentUrl":"https:\/\/www.federassantas.org.br\/novosite\/wp-content\/uploads\/2021\/12\/logo.png","width":243,"height":59,"caption":"Federassantas"},"image":{"@id":"https:\/\/www.federassantas.org.br\/novosite\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.federassantas.org.br\/novosite\/#\/schema\/person\/75fed98158349313fe56175f232f513c","name":"admin-federas","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.federassantas.org.br\/novosite\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/2a02d7dda59fe8dc6b7ffd3f652e2efede5ccf0dd89dfdc8137c5517f3de8407?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/2a02d7dda59fe8dc6b7ffd3f652e2efede5ccf0dd89dfdc8137c5517f3de8407?s=96&d=mm&r=g","caption":"admin-federas"},"sameAs":["https:\/\/www.federassantas.org.br\/novosite\/"],"url":"https:\/\/www.federassantas.org.br\/novosite\/author\/admin-federas\/"}]}},"_links":{"self":[{"href":"https:\/\/www.federassantas.org.br\/novosite\/wp-json\/wp\/v2\/posts\/13608","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.federassantas.org.br\/novosite\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.federassantas.org.br\/novosite\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.federassantas.org.br\/novosite\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.federassantas.org.br\/novosite\/wp-json\/wp\/v2\/comments?post=13608"}],"version-history":[{"count":0,"href":"https:\/\/www.federassantas.org.br\/novosite\/wp-json\/wp\/v2\/posts\/13608\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.federassantas.org.br\/novosite\/wp-json\/wp\/v2\/media\/13611"}],"wp:attachment":[{"href":"https:\/\/www.federassantas.org.br\/novosite\/wp-json\/wp\/v2\/media?parent=13608"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.federassantas.org.br\/novosite\/wp-json\/wp\/v2\/categories?post=13608"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.federassantas.org.br\/novosite\/wp-json\/wp\/v2\/tags?post=13608"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}