{"id":24390,"date":"2022-04-28T18:09:20","date_gmt":"2022-04-28T21:09:20","guid":{"rendered":"https:\/\/federasbackup.meltcomunicacao.com.br\/?p=23951"},"modified":"2022-11-03T15:00:24","modified_gmt":"2022-11-03T18:00:24","slug":"webserie-do-grupo-santa-casa-bh-esclarece-principais-duvidas-sobre-epilepsia-de-forma-divertida-e-informativa","status":"publish","type":"post","link":"https:\/\/www.federassantas.org.br\/novosite\/webserie-do-grupo-santa-casa-bh-esclarece-principais-duvidas-sobre-epilepsia-de-forma-divertida-e-informativa\/","title":{"rendered":"Webs\u00e9rie do Grupo Santa Casa BH esclarece principais d\u00favidas sobre epilepsia de forma divertida e informativa"},"content":{"rendered":"\r\n<h5 class=\"wp-block-heading\"><em>Objetivo \u00e9 disponibilizar informa\u00e7\u00f5es relevantes sobre a condi\u00e7\u00e3o neurol\u00f3gica que afeta 2% da popula\u00e7\u00e3o brasileira e acomete crian\u00e7as e adultos.<\/em><\/h5>\r\n\r\n\r\n\r\n<p>De acordo com a Organiza\u00e7\u00e3o Mundial da Sa\u00fade (OMS), 2% da popula\u00e7\u00e3o brasileira tem epilepsia e, no mundo inteiro, a doen\u00e7a atinge mais de 50 milh\u00f5es de pessoas. Ela\u00a0 se\u00a0 caracteriza por manifesta\u00e7\u00f5es cl\u00ednicas de uma descarga anormal de neur\u00f4nios que causa crises epil\u00e9pticas em intervalos vari\u00e1veis de tempo. Mas o fato \u00e9 que nem sempre essas crises s\u00e3o identificadas e muitas pessoas nem sabem que t\u00eam.\u00a0<\/p>\r\n\r\n\r\n\r\n<p>Para esclarecer as principais d\u00favidas sobre a epilepsia, como identific\u00e1-la rapidamente e tamb\u00e9m evitar o estigma sobre uma doen\u00e7a t\u00e3o comum, o Grupo Santa Casa BH (GSCBH) disponibiliza, a partir desta ter\u00e7a-feira, 26, em seu canal no YouTube, um epis\u00f3dio especial da webs\u00e9rie Quebra-Cabe\u00e7a, apresentado pela jornalista Ang\u00e9lica Hodge e com participa\u00e7\u00e3o de m\u00e9dicos, psic\u00f3logos e assistentes sociais..\u00a0<\/p>\r\n\r\n\r\n\r\n<p>De forma divertida e leve, ser\u00e3o abordados temas como a detec\u00e7\u00e3o da doen\u00e7a em crian\u00e7as e adultos, a ocorr\u00eancia da gravidez em pessoas epil\u00e9pticas, tratamentos, exames e primeiros socorros durante uma convuls\u00e3o.\u00a0<\/p>\r\n\r\n\r\n\r\n<p>A webs\u00e9rie Quebra-Cabe\u00e7a, no ar desde agosto de 2021, j\u00e1 disponibilizou para o p\u00fablico epis\u00f3dios sobre amamenta\u00e7\u00e3o, parto humanizado, doa\u00e7\u00e3o de \u00f3rg\u00e3os, c\u00e2ncer de mama, c\u00e2ncer de pr\u00f3stata, gripe, transtornos alimentares e automedica\u00e7\u00e3o, sempre com uma linguagem moderna e investindo na aproxima\u00e7\u00e3o com quem consome conte\u00fados de youtubers. Todo o conte\u00fado fica disponibilizado no canal da Santa Casa BH no Youtube.\u00a0<\/p>\r\n\r\n\r\n\r\n<p><strong>Servi\u00e7o:<\/strong><\/p>\r\n\r\n\r\n\r\n<p>Webs\u00e9rie Quebra-Cabe\u00e7a &#8211; Especial Epilepsia<\/p>\r\n\r\n\r\n\r\n<p>Estreia: ter\u00e7a-feira, 26 de abril.Canal: <a href=\"https:\/\/youtu.be\/UrlgbLDZiBc\" target=\"_blank\" rel=\"noreferrer noopener\">YouTube do Grupo Santa Casa BH<\/a><\/p>\r\n","protected":false},"excerpt":{"rendered":"<p>Objetivo \u00e9 disponibilizar informa\u00e7\u00f5es relevantes sobre a condi\u00e7\u00e3o neurol\u00f3gica que afeta 2% da popula\u00e7\u00e3o brasileira e acomete crian\u00e7as e adultos. De acordo com a Organiza\u00e7\u00e3o Mundial da Sa\u00fade (OMS), 2% da popula\u00e7\u00e3o brasileira tem epilepsia e, no mundo inteiro, a doen\u00e7a atinge mais de 50 milh\u00f5es de pessoas. Ela\u00a0 se\u00a0 caracteriza por manifesta\u00e7\u00f5es cl\u00ednicas de [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":23952,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[140,141,139,247],"tags":[],"class_list":["post-24390","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias","category-noticias-federassantas","category-noticias-filiados","category-regional-central-metropolitana"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Webs\u00e9rie do Grupo Santa Casa BH esclarece principais d\u00favidas sobre epilepsia de forma divertida e informativa - Federassantas<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.federassantas.org.br\/novosite\/webserie-do-grupo-santa-casa-bh-esclarece-principais-duvidas-sobre-epilepsia-de-forma-divertida-e-informativa\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Webs\u00e9rie do Grupo Santa Casa BH esclarece principais d\u00favidas sobre epilepsia de forma divertida e informativa - Federassantas\" \/>\n<meta property=\"og:description\" content=\"Objetivo \u00e9 disponibilizar informa\u00e7\u00f5es relevantes sobre a condi\u00e7\u00e3o neurol\u00f3gica que afeta 2% da popula\u00e7\u00e3o brasileira e acomete crian\u00e7as e adultos. De acordo com a Organiza\u00e7\u00e3o Mundial da Sa\u00fade (OMS), 2% da popula\u00e7\u00e3o brasileira tem epilepsia e, no mundo inteiro, a doen\u00e7a atinge mais de 50 milh\u00f5es de pessoas. Ela\u00a0 se\u00a0 caracteriza por manifesta\u00e7\u00f5es cl\u00ednicas de [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.federassantas.org.br\/novosite\/webserie-do-grupo-santa-casa-bh-esclarece-principais-duvidas-sobre-epilepsia-de-forma-divertida-e-informativa\/\" \/>\n<meta property=\"og:site_name\" content=\"Federassantas\" \/>\n<meta property=\"article:published_time\" content=\"2022-04-28T21:09:20+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-11-03T18:00:24+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.federassantas.org.br\/novosite\/wp-content\/uploads\/2022\/02\/Foto-5-1-scaled-2.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1154\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"admin-federas\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin-federas\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.federassantas.org.br\/novosite\/webserie-do-grupo-santa-casa-bh-esclarece-principais-duvidas-sobre-epilepsia-de-forma-divertida-e-informativa\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.federassantas.org.br\/novosite\/webserie-do-grupo-santa-casa-bh-esclarece-principais-duvidas-sobre-epilepsia-de-forma-divertida-e-informativa\/\"},\"author\":{\"name\":\"admin-federas\",\"@id\":\"https:\/\/www.federassantas.org.br\/novosite\/#\/schema\/person\/75fed98158349313fe56175f232f513c\"},\"headline\":\"Webs\u00e9rie do Grupo Santa Casa BH esclarece principais d\u00favidas sobre epilepsia de forma divertida e informativa\",\"datePublished\":\"2022-04-28T21:09:20+00:00\",\"dateModified\":\"2022-11-03T18:00:24+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.federassantas.org.br\/novosite\/webserie-do-grupo-santa-casa-bh-esclarece-principais-duvidas-sobre-epilepsia-de-forma-divertida-e-informativa\/\"},\"wordCount\":321,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/www.federassantas.org.br\/novosite\/#organization\"},\"image\":{\"@id\":\"https:\/\/www.federassantas.org.br\/novosite\/webserie-do-grupo-santa-casa-bh-esclarece-principais-duvidas-sobre-epilepsia-de-forma-divertida-e-informativa\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.federassantas.org.br\/novosite\/wp-content\/uploads\/2022\/02\/Foto-5-1-scaled-2.jpg\",\"articleSection\":[\"Not\u00edcias\",\"Not\u00edcias Federassantas\",\"Not\u00edcias filiados\",\"Regional Central \/ Metropolitana\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/www.federassantas.org.br\/novosite\/webserie-do-grupo-santa-casa-bh-esclarece-principais-duvidas-sobre-epilepsia-de-forma-divertida-e-informativa\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.federassantas.org.br\/novosite\/webserie-do-grupo-santa-casa-bh-esclarece-principais-duvidas-sobre-epilepsia-de-forma-divertida-e-informativa\/\",\"url\":\"https:\/\/www.federassantas.org.br\/novosite\/webserie-do-grupo-santa-casa-bh-esclarece-principais-duvidas-sobre-epilepsia-de-forma-divertida-e-informativa\/\",\"name\":\"Webs\u00e9rie do Grupo Santa Casa BH esclarece principais d\u00favidas sobre epilepsia de forma divertida e informativa - Federassantas\",\"isPartOf\":{\"@id\":\"https:\/\/www.federassantas.org.br\/novosite\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.federassantas.org.br\/novosite\/webserie-do-grupo-santa-casa-bh-esclarece-principais-duvidas-sobre-epilepsia-de-forma-divertida-e-informativa\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.federassantas.org.br\/novosite\/webserie-do-grupo-santa-casa-bh-esclarece-principais-duvidas-sobre-epilepsia-de-forma-divertida-e-informativa\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.federassantas.org.br\/novosite\/wp-content\/uploads\/2022\/02\/Foto-5-1-scaled-2.jpg\",\"datePublished\":\"2022-04-28T21:09:20+00:00\",\"dateModified\":\"2022-11-03T18:00:24+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.federassantas.org.br\/novosite\/webserie-do-grupo-santa-casa-bh-esclarece-principais-duvidas-sobre-epilepsia-de-forma-divertida-e-informativa\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.federassantas.org.br\/novosite\/webserie-do-grupo-santa-casa-bh-esclarece-principais-duvidas-sobre-epilepsia-de-forma-divertida-e-informativa\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.federassantas.org.br\/novosite\/webserie-do-grupo-santa-casa-bh-esclarece-principais-duvidas-sobre-epilepsia-de-forma-divertida-e-informativa\/#primaryimage\",\"url\":\"https:\/\/www.federassantas.org.br\/novosite\/wp-content\/uploads\/2022\/02\/Foto-5-1-scaled-2.jpg\",\"contentUrl\":\"https:\/\/www.federassantas.org.br\/novosite\/wp-content\/uploads\/2022\/02\/Foto-5-1-scaled-2.jpg\",\"width\":2560,\"height\":1154},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.federassantas.org.br\/novosite\/webserie-do-grupo-santa-casa-bh-esclarece-principais-duvidas-sobre-epilepsia-de-forma-divertida-e-informativa\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/www.federassantas.org.br\/novosite\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Webs\u00e9rie do Grupo Santa Casa BH esclarece principais d\u00favidas sobre epilepsia de forma divertida e informativa\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.federassantas.org.br\/novosite\/#website\",\"url\":\"https:\/\/www.federassantas.org.br\/novosite\/\",\"name\":\"Federassantas\",\"description\":\"Fed. das Santas Casas e Hospitais Filantr\u00f3picos de MG\",\"publisher\":{\"@id\":\"https:\/\/www.federassantas.org.br\/novosite\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.federassantas.org.br\/novosite\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.federassantas.org.br\/novosite\/#organization\",\"name\":\"Federassantas\",\"url\":\"https:\/\/www.federassantas.org.br\/novosite\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.federassantas.org.br\/novosite\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.federassantas.org.br\/novosite\/wp-content\/uploads\/2021\/12\/logo.png\",\"contentUrl\":\"https:\/\/www.federassantas.org.br\/novosite\/wp-content\/uploads\/2021\/12\/logo.png\",\"width\":243,\"height\":59,\"caption\":\"Federassantas\"},\"image\":{\"@id\":\"https:\/\/www.federassantas.org.br\/novosite\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.federassantas.org.br\/novosite\/#\/schema\/person\/75fed98158349313fe56175f232f513c\",\"name\":\"admin-federas\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.federassantas.org.br\/novosite\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/2a02d7dda59fe8dc6b7ffd3f652e2efede5ccf0dd89dfdc8137c5517f3de8407?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/2a02d7dda59fe8dc6b7ffd3f652e2efede5ccf0dd89dfdc8137c5517f3de8407?s=96&d=mm&r=g\",\"caption\":\"admin-federas\"},\"sameAs\":[\"https:\/\/www.federassantas.org.br\/novosite\/\"],\"url\":\"https:\/\/www.federassantas.org.br\/novosite\/author\/admin-federas\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Webs\u00e9rie do Grupo Santa Casa BH esclarece principais d\u00favidas sobre epilepsia de forma divertida e informativa - Federassantas","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.federassantas.org.br\/novosite\/webserie-do-grupo-santa-casa-bh-esclarece-principais-duvidas-sobre-epilepsia-de-forma-divertida-e-informativa\/","og_locale":"pt_BR","og_type":"article","og_title":"Webs\u00e9rie do Grupo Santa Casa BH esclarece principais d\u00favidas sobre epilepsia de forma divertida e informativa - Federassantas","og_description":"Objetivo \u00e9 disponibilizar informa\u00e7\u00f5es relevantes sobre a condi\u00e7\u00e3o neurol\u00f3gica que afeta 2% da popula\u00e7\u00e3o brasileira e acomete crian\u00e7as e adultos. De acordo com a Organiza\u00e7\u00e3o Mundial da Sa\u00fade (OMS), 2% da popula\u00e7\u00e3o brasileira tem epilepsia e, no mundo inteiro, a doen\u00e7a atinge mais de 50 milh\u00f5es de pessoas. Ela\u00a0 se\u00a0 caracteriza por manifesta\u00e7\u00f5es cl\u00ednicas de [&hellip;]","og_url":"https:\/\/www.federassantas.org.br\/novosite\/webserie-do-grupo-santa-casa-bh-esclarece-principais-duvidas-sobre-epilepsia-de-forma-divertida-e-informativa\/","og_site_name":"Federassantas","article_published_time":"2022-04-28T21:09:20+00:00","article_modified_time":"2022-11-03T18:00:24+00:00","og_image":[{"width":2560,"height":1154,"url":"https:\/\/www.federassantas.org.br\/novosite\/wp-content\/uploads\/2022\/02\/Foto-5-1-scaled-2.jpg","type":"image\/jpeg"}],"author":"admin-federas","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"admin-federas","Est. tempo de leitura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.federassantas.org.br\/novosite\/webserie-do-grupo-santa-casa-bh-esclarece-principais-duvidas-sobre-epilepsia-de-forma-divertida-e-informativa\/#article","isPartOf":{"@id":"https:\/\/www.federassantas.org.br\/novosite\/webserie-do-grupo-santa-casa-bh-esclarece-principais-duvidas-sobre-epilepsia-de-forma-divertida-e-informativa\/"},"author":{"name":"admin-federas","@id":"https:\/\/www.federassantas.org.br\/novosite\/#\/schema\/person\/75fed98158349313fe56175f232f513c"},"headline":"Webs\u00e9rie do Grupo Santa Casa BH esclarece principais d\u00favidas sobre epilepsia de forma divertida e informativa","datePublished":"2022-04-28T21:09:20+00:00","dateModified":"2022-11-03T18:00:24+00:00","mainEntityOfPage":{"@id":"https:\/\/www.federassantas.org.br\/novosite\/webserie-do-grupo-santa-casa-bh-esclarece-principais-duvidas-sobre-epilepsia-de-forma-divertida-e-informativa\/"},"wordCount":321,"commentCount":0,"publisher":{"@id":"https:\/\/www.federassantas.org.br\/novosite\/#organization"},"image":{"@id":"https:\/\/www.federassantas.org.br\/novosite\/webserie-do-grupo-santa-casa-bh-esclarece-principais-duvidas-sobre-epilepsia-de-forma-divertida-e-informativa\/#primaryimage"},"thumbnailUrl":"https:\/\/www.federassantas.org.br\/novosite\/wp-content\/uploads\/2022\/02\/Foto-5-1-scaled-2.jpg","articleSection":["Not\u00edcias","Not\u00edcias Federassantas","Not\u00edcias filiados","Regional Central \/ Metropolitana"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.federassantas.org.br\/novosite\/webserie-do-grupo-santa-casa-bh-esclarece-principais-duvidas-sobre-epilepsia-de-forma-divertida-e-informativa\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.federassantas.org.br\/novosite\/webserie-do-grupo-santa-casa-bh-esclarece-principais-duvidas-sobre-epilepsia-de-forma-divertida-e-informativa\/","url":"https:\/\/www.federassantas.org.br\/novosite\/webserie-do-grupo-santa-casa-bh-esclarece-principais-duvidas-sobre-epilepsia-de-forma-divertida-e-informativa\/","name":"Webs\u00e9rie do Grupo Santa Casa BH esclarece principais d\u00favidas sobre epilepsia de forma divertida e informativa - Federassantas","isPartOf":{"@id":"https:\/\/www.federassantas.org.br\/novosite\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.federassantas.org.br\/novosite\/webserie-do-grupo-santa-casa-bh-esclarece-principais-duvidas-sobre-epilepsia-de-forma-divertida-e-informativa\/#primaryimage"},"image":{"@id":"https:\/\/www.federassantas.org.br\/novosite\/webserie-do-grupo-santa-casa-bh-esclarece-principais-duvidas-sobre-epilepsia-de-forma-divertida-e-informativa\/#primaryimage"},"thumbnailUrl":"https:\/\/www.federassantas.org.br\/novosite\/wp-content\/uploads\/2022\/02\/Foto-5-1-scaled-2.jpg","datePublished":"2022-04-28T21:09:20+00:00","dateModified":"2022-11-03T18:00:24+00:00","breadcrumb":{"@id":"https:\/\/www.federassantas.org.br\/novosite\/webserie-do-grupo-santa-casa-bh-esclarece-principais-duvidas-sobre-epilepsia-de-forma-divertida-e-informativa\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.federassantas.org.br\/novosite\/webserie-do-grupo-santa-casa-bh-esclarece-principais-duvidas-sobre-epilepsia-de-forma-divertida-e-informativa\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.federassantas.org.br\/novosite\/webserie-do-grupo-santa-casa-bh-esclarece-principais-duvidas-sobre-epilepsia-de-forma-divertida-e-informativa\/#primaryimage","url":"https:\/\/www.federassantas.org.br\/novosite\/wp-content\/uploads\/2022\/02\/Foto-5-1-scaled-2.jpg","contentUrl":"https:\/\/www.federassantas.org.br\/novosite\/wp-content\/uploads\/2022\/02\/Foto-5-1-scaled-2.jpg","width":2560,"height":1154},{"@type":"BreadcrumbList","@id":"https:\/\/www.federassantas.org.br\/novosite\/webserie-do-grupo-santa-casa-bh-esclarece-principais-duvidas-sobre-epilepsia-de-forma-divertida-e-informativa\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/www.federassantas.org.br\/novosite\/"},{"@type":"ListItem","position":2,"name":"Webs\u00e9rie do Grupo Santa Casa BH esclarece principais d\u00favidas sobre epilepsia de forma divertida e informativa"}]},{"@type":"WebSite","@id":"https:\/\/www.federassantas.org.br\/novosite\/#website","url":"https:\/\/www.federassantas.org.br\/novosite\/","name":"Federassantas","description":"Fed. das Santas Casas e Hospitais Filantr\u00f3picos de MG","publisher":{"@id":"https:\/\/www.federassantas.org.br\/novosite\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.federassantas.org.br\/novosite\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/www.federassantas.org.br\/novosite\/#organization","name":"Federassantas","url":"https:\/\/www.federassantas.org.br\/novosite\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.federassantas.org.br\/novosite\/#\/schema\/logo\/image\/","url":"https:\/\/www.federassantas.org.br\/novosite\/wp-content\/uploads\/2021\/12\/logo.png","contentUrl":"https:\/\/www.federassantas.org.br\/novosite\/wp-content\/uploads\/2021\/12\/logo.png","width":243,"height":59,"caption":"Federassantas"},"image":{"@id":"https:\/\/www.federassantas.org.br\/novosite\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.federassantas.org.br\/novosite\/#\/schema\/person\/75fed98158349313fe56175f232f513c","name":"admin-federas","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.federassantas.org.br\/novosite\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/2a02d7dda59fe8dc6b7ffd3f652e2efede5ccf0dd89dfdc8137c5517f3de8407?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/2a02d7dda59fe8dc6b7ffd3f652e2efede5ccf0dd89dfdc8137c5517f3de8407?s=96&d=mm&r=g","caption":"admin-federas"},"sameAs":["https:\/\/www.federassantas.org.br\/novosite\/"],"url":"https:\/\/www.federassantas.org.br\/novosite\/author\/admin-federas\/"}]}},"_links":{"self":[{"href":"https:\/\/www.federassantas.org.br\/novosite\/wp-json\/wp\/v2\/posts\/24390","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.federassantas.org.br\/novosite\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.federassantas.org.br\/novosite\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.federassantas.org.br\/novosite\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.federassantas.org.br\/novosite\/wp-json\/wp\/v2\/comments?post=24390"}],"version-history":[{"count":1,"href":"https:\/\/www.federassantas.org.br\/novosite\/wp-json\/wp\/v2\/posts\/24390\/revisions"}],"predecessor-version":[{"id":25845,"href":"https:\/\/www.federassantas.org.br\/novosite\/wp-json\/wp\/v2\/posts\/24390\/revisions\/25845"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.federassantas.org.br\/novosite\/wp-json\/wp\/v2\/media\/23952"}],"wp:attachment":[{"href":"https:\/\/www.federassantas.org.br\/novosite\/wp-json\/wp\/v2\/media?parent=24390"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.federassantas.org.br\/novosite\/wp-json\/wp\/v2\/categories?post=24390"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.federassantas.org.br\/novosite\/wp-json\/wp\/v2\/tags?post=24390"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}