{"id":31403,"date":"2024-02-05T09:39:15","date_gmt":"2024-02-05T12:39:15","guid":{"rendered":"https:\/\/www.federassantas.org.br\/novosite\/?p=31403"},"modified":"2024-02-05T09:40:54","modified_gmt":"2024-02-05T12:40:54","slug":"neurocirurgiao-da-santa-casa-de-montes-claros-e-destaque-em-revista-internacional-norte-americana","status":"publish","type":"post","link":"https:\/\/www.federassantas.org.br\/novosite\/neurocirurgiao-da-santa-casa-de-montes-claros-e-destaque-em-revista-internacional-norte-americana\/","title":{"rendered":"Neurocirurgi\u00e3o da Santa Casa de Montes Claros \u00e9 destaque em revista internacional norte-americana"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"31403\" class=\"elementor elementor-31403\" data-elementor-post-type=\"post\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-054e885 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"054e885\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-add2b87\" data-id=\"add2b87\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-bcae4d9 elementor-widget elementor-widget-heading\" data-id=\"bcae4d9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Neurocirurgi\u00e3o da Santa Casa de Montes Claros \u00e9 destaque em revista internacional norte-americana<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-bd960c0 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"bd960c0\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-62d46c8\" data-id=\"62d46c8\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-0ef08e1 elementor-widget elementor-widget-text-editor\" data-id=\"0ef08e1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p dir=\"ltr\">Neste m\u00eas de janeiro, o trabalho desenvolvido pelo neurocirurgi\u00e3o da Santa Casa Montes Claros, Dr. Lu\u00eds Gustavo Biondi, foi capa da revista internacional norte-americana OperativeNeurosurgery, que \u00e9 considerada uma das mais renomadas revistas de neurocirurgia do mundo, al\u00e9m de integrar o CNS (Congress ofNeurologicalSurgeons).O tema do assunto publicado foi \u201cT\u00e9cnica de pun\u00e7\u00e3o ventricular transorbital: uma abordagem anat\u00f4mica\u201d.&nbsp;<\/p>\n<p dir=\"ltr\">Dr Lu\u00eds Gustavo Biondi, que tamb\u00e9m \u00e9 fellowship em neurocirurgia vascular pela Universidade Federal de S\u00e3o Paulo (UNIFESP), explica que a publica\u00e7\u00e3o trata-se da descri\u00e7\u00e3o de uma t\u00e9cnica cir\u00fargica aplicada em situa\u00e7\u00f5es de emerg\u00eancia neurol\u00f3gica. \u201cDe forma mais espec\u00edfica, \u00e9 um procedimento neurocir\u00fargico a ser utilizado em situa\u00e7\u00f5es de vida ou morte, onde h\u00e1 um grande aumento da press\u00e3o intracraniana secund\u00e1ria e um quadro de hidrocefalia descompensada. Nesta t\u00e9cnica, inserimos uma agulha canulada no rebordo orbit\u00e1rio superior e seguimos em um trajeto intracerebral at\u00e9 atingirmos o ventr\u00edculo cerebral, permitindo a drenagem de l\u00edquido cefalorraquidiano e aliviando, consequentemente, a press\u00e3o intracraniana\u201d, esclarece o m\u00e9dico.<\/p>\n<p dir=\"ltr\">O reconhecimento internacional do Dr. Lu\u00eds Gustavo Biondi destaca n\u00e3o apenas sua habilidade excepcional, mas tamb\u00e9m a contribui\u00e7\u00e3o significativa da Santa Casa Montes Claros para o avan\u00e7o da medicina, conforme ressalta o superintendente Maur\u00edcio S\u00e9rgio Sousa e Silva. \u201cEstamos comprometidos com a excel\u00eancia e a inova\u00e7\u00e3o em prol da sa\u00fade e bem-estar da popula\u00e7\u00e3o da nossa regi\u00e3o. Esse reconhecimento demonstra ainda a excel\u00eancia dos programas de resid\u00eancia m\u00e9dica oferecidos no hospital, uma vez que o Dr. Biondi realizou na Santa Casa Montes Claros sua especializa\u00e7\u00e3o em neurocirurgia. Aproveito para parabeniz\u00e1-lo pela conquista e tamb\u00e9m registrar meu agradecimento a todo o time envolvido nos programas de resid\u00eancia\u201d, diz.&nbsp;<\/p>\n<p dir=\"ltr\">Dr. Biondi explica que o trabalho foi desenvolvido atrav\u00e9s de uma parceria entre a Santa Casa Montes Claros, Universidade Federal de S\u00e3o Paulo e o Hospital Benefic\u00eancia Portuguesa. \u201cRealizamos longa an\u00e1lise de dados com exames de imagem, tomografia computadorizada de cr\u00e2nio e face,&nbsp; a fim de encontrar medidas com relev\u00e2ncia estat\u00edstica que pudessem promover a melhor execu\u00e7\u00e3o da t\u00e9cnica, incluindo melhor local da pun\u00e7\u00e3o, angula\u00e7\u00e3o e dist\u00e2ncia a ser percorrida com a agulha de pun\u00e7\u00e3o. No laborat\u00f3rio de neuroanatomia microcir\u00fargica, aplicamos a t\u00e9cnica em cad\u00e1veres a fim de se comprovar os dados fornecidos pela equipe de estat\u00edstica e validarmos a execu\u00e7\u00e3o desta t\u00e9cnica neurocir\u00fargica\u201d, esclarece o neurocirurgi\u00e3o.<\/p>\n<p dir=\"ltr\">Ele finaliza ressaltando que a import\u00e2ncia da publica\u00e7\u00e3o e da t\u00e9cnica em si \u00e9 o fato de poder proporcionar uma redu\u00e7\u00e3o imediata da press\u00e3o intracraniana em casos de hidrocefalia descompensada, permitindo que pacientes graves tenham um mais tempo de vida e, consequentemente,consigam chegar ao hospital de refer\u00eancia e receber o tratamento definitivo. \u201cEm algumas localidades mais isoladas do pa\u00eds, o acesso ao neurocirurgi\u00e3o em situa\u00e7\u00f5es de emerg\u00eancia nem sempre \u00e9 realizado de maneira \u00e1gil. Tal fato corrobora para que situa\u00e7\u00f5es, muitas vezes trat\u00e1veis, tenham desfechos tr\u00e1gicos devido a demora para transporte, avalia\u00e7\u00e3o e condutas espec\u00edficas do neurocirurgi\u00e3o\u201d, finaliza.<\/p>\n<p dir=\"ltr\">A publica\u00e7\u00e3o do trabalho na \u00edntegra pode ser conferido em:&nbsp;<\/p>\n<p dir=\"ltr\"><a href=\"https:\/\/journals.lww.com\/onsonline\/abstract\/2024\/01000\/the_technique_for_transorbital_ventricular.9.aspx?context=featuredarticles&amp;collectionid=51#\" target=\"_blank\" rel=\"noopener\" data-saferedirecturl=\"https:\/\/www.google.com\/url?q=https:\/\/journals.lww.com\/onsonline\/abstract\/2024\/01000\/the_technique_for_transorbital_ventricular.9.aspx?context%3Dfeaturedarticles%26collectionid%3D51%23&amp;source=gmail&amp;ust=1706623077424000&amp;usg=AOvVaw1XFTw90KfiseTqadOWaaFk\">https:\/\/journals.lww.com\/<wbr>onsonline\/abstract\/2024\/01000\/<wbr>the_technique_for_<wbr>transorbital_ventricular.9.<wbr>aspx?context=featuredarticles&amp;<wbr>collectionid=51#<\/a><\/p>\n<p dir=\"ltr\">Assessoria de Imprensa: Ana Paula Paix\u00e3o<\/p>\n<div>\n<div class=\"gmail_signature\" dir=\"ltr\" data-smartmail=\"gmail_signature\">\n<div dir=\"ltr\">\n<div>\n<div dir=\"ltr\">\n<div>\n<div dir=\"ltr\">\n<div>\n<div dir=\"ltr\">\n<div>\n<div dir=\"ltr\">\n<div>\n<div dir=\"ltr\">\n<div>\n<div dir=\"ltr\">\n<div>\n<div dir=\"ltr\">\n<div>\n<div dir=\"ltr\">\n<div>\n<div dir=\"ltr\">\n<div>\n<div>\n<div dir=\"ltr\">\n<div>\n<div dir=\"ltr\"><em style=\"color: var( --e-global-color-text ); font-size: 0.9rem;\">Gostaria de divulgar informa\u00e7\u00f5es do seu hospital no site da Federassantas? Acesse a&nbsp;<a href=\"https:\/\/www.federassantas.org.br\/novosite\/comunicacao\/\">p\u00e1gina da comunica\u00e7\u00e3o<\/a>&nbsp;e nos envie o seu release.<\/em><\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Neurocirurgi\u00e3o da Santa Casa de Montes Claros \u00e9 destaque em revista internacional norte-americana Neste m\u00eas de janeiro, o trabalho desenvolvido pelo neurocirurgi\u00e3o da Santa Casa Montes Claros, Dr. Lu\u00eds Gustavo Biondi, foi capa da revista internacional norte-americana OperativeNeurosurgery, que \u00e9 considerada uma das mais renomadas revistas de neurocirurgia do mundo, al\u00e9m de integrar o CNS [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":31405,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[139,244],"tags":[462,709,457],"class_list":["post-31403","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias-filiados","category-regional-norte","tag-destaque","tag-neurocirurgiao","tag-santa-casa-montes-claros"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Neurocirurgi\u00e3o da Santa Casa de Montes Claros \u00e9 destaque em revista internacional norte-americana - Federassantas<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.federassantas.org.br\/novosite\/neurocirurgiao-da-santa-casa-de-montes-claros-e-destaque-em-revista-internacional-norte-americana\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Neurocirurgi\u00e3o da Santa Casa de Montes Claros \u00e9 destaque em revista internacional norte-americana - Federassantas\" \/>\n<meta property=\"og:description\" content=\"Neurocirurgi\u00e3o da Santa Casa de Montes Claros \u00e9 destaque em revista internacional norte-americana Neste m\u00eas de janeiro, o trabalho desenvolvido pelo neurocirurgi\u00e3o da Santa Casa Montes Claros, Dr. Lu\u00eds Gustavo Biondi, foi capa da revista internacional norte-americana OperativeNeurosurgery, que \u00e9 considerada uma das mais renomadas revistas de neurocirurgia do mundo, al\u00e9m de integrar o CNS [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.federassantas.org.br\/novosite\/neurocirurgiao-da-santa-casa-de-montes-claros-e-destaque-em-revista-internacional-norte-americana\/\" \/>\n<meta property=\"og:site_name\" content=\"Federassantas\" \/>\n<meta property=\"article:published_time\" content=\"2024-02-05T12:39:15+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-02-05T12:40:54+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.federassantas.org.br\/novosite\/wp-content\/uploads\/2024\/02\/DR-BIONDI-2-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"2560\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"admin-federas\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin-federas\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.federassantas.org.br\/novosite\/neurocirurgiao-da-santa-casa-de-montes-claros-e-destaque-em-revista-internacional-norte-americana\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.federassantas.org.br\/novosite\/neurocirurgiao-da-santa-casa-de-montes-claros-e-destaque-em-revista-internacional-norte-americana\/\"},\"author\":{\"name\":\"admin-federas\",\"@id\":\"https:\/\/www.federassantas.org.br\/novosite\/#\/schema\/person\/75fed98158349313fe56175f232f513c\"},\"headline\":\"Neurocirurgi\u00e3o da Santa Casa de Montes Claros \u00e9 destaque em revista internacional norte-americana\",\"datePublished\":\"2024-02-05T12:39:15+00:00\",\"dateModified\":\"2024-02-05T12:40:54+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.federassantas.org.br\/novosite\/neurocirurgiao-da-santa-casa-de-montes-claros-e-destaque-em-revista-internacional-norte-americana\/\"},\"wordCount\":645,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/www.federassantas.org.br\/novosite\/#organization\"},\"image\":{\"@id\":\"https:\/\/www.federassantas.org.br\/novosite\/neurocirurgiao-da-santa-casa-de-montes-claros-e-destaque-em-revista-internacional-norte-americana\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.federassantas.org.br\/novosite\/wp-content\/uploads\/2024\/02\/DR-BIONDI-2-scaled.jpg\",\"keywords\":[\"Destaque\",\"neurocirurgi\u00e3o\",\"Santa Casa Montes Claros\"],\"articleSection\":[\"Not\u00edcias filiados\",\"Regional Norte\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/www.federassantas.org.br\/novosite\/neurocirurgiao-da-santa-casa-de-montes-claros-e-destaque-em-revista-internacional-norte-americana\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.federassantas.org.br\/novosite\/neurocirurgiao-da-santa-casa-de-montes-claros-e-destaque-em-revista-internacional-norte-americana\/\",\"url\":\"https:\/\/www.federassantas.org.br\/novosite\/neurocirurgiao-da-santa-casa-de-montes-claros-e-destaque-em-revista-internacional-norte-americana\/\",\"name\":\"Neurocirurgi\u00e3o da Santa Casa de Montes Claros \u00e9 destaque em revista internacional norte-americana - Federassantas\",\"isPartOf\":{\"@id\":\"https:\/\/www.federassantas.org.br\/novosite\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.federassantas.org.br\/novosite\/neurocirurgiao-da-santa-casa-de-montes-claros-e-destaque-em-revista-internacional-norte-americana\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.federassantas.org.br\/novosite\/neurocirurgiao-da-santa-casa-de-montes-claros-e-destaque-em-revista-internacional-norte-americana\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.federassantas.org.br\/novosite\/wp-content\/uploads\/2024\/02\/DR-BIONDI-2-scaled.jpg\",\"datePublished\":\"2024-02-05T12:39:15+00:00\",\"dateModified\":\"2024-02-05T12:40:54+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.federassantas.org.br\/novosite\/neurocirurgiao-da-santa-casa-de-montes-claros-e-destaque-em-revista-internacional-norte-americana\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.federassantas.org.br\/novosite\/neurocirurgiao-da-santa-casa-de-montes-claros-e-destaque-em-revista-internacional-norte-americana\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.federassantas.org.br\/novosite\/neurocirurgiao-da-santa-casa-de-montes-claros-e-destaque-em-revista-internacional-norte-americana\/#primaryimage\",\"url\":\"https:\/\/www.federassantas.org.br\/novosite\/wp-content\/uploads\/2024\/02\/DR-BIONDI-2-scaled.jpg\",\"contentUrl\":\"https:\/\/www.federassantas.org.br\/novosite\/wp-content\/uploads\/2024\/02\/DR-BIONDI-2-scaled.jpg\",\"width\":1920,\"height\":2560},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.federassantas.org.br\/novosite\/neurocirurgiao-da-santa-casa-de-montes-claros-e-destaque-em-revista-internacional-norte-americana\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/www.federassantas.org.br\/novosite\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Neurocirurgi\u00e3o da Santa Casa de Montes Claros \u00e9 destaque em revista internacional norte-americana\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.federassantas.org.br\/novosite\/#website\",\"url\":\"https:\/\/www.federassantas.org.br\/novosite\/\",\"name\":\"Federassantas\",\"description\":\"Entidade de representa\u00e7\u00e3o e fortalecimento das Santas Casas, hospitais filantr\u00f3picos e entidades beneficentes de sa\u00fade de Minas Gerais, atuando na defesa institucional, qualifica\u00e7\u00e3o da gest\u00e3o e sustentabilidade do setor.\",\"publisher\":{\"@id\":\"https:\/\/www.federassantas.org.br\/novosite\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.federassantas.org.br\/novosite\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.federassantas.org.br\/novosite\/#organization\",\"name\":\"Federassantas\",\"url\":\"https:\/\/www.federassantas.org.br\/novosite\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.federassantas.org.br\/novosite\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.federassantas.org.br\/novosite\/wp-content\/uploads\/2021\/12\/logo.png\",\"contentUrl\":\"https:\/\/www.federassantas.org.br\/novosite\/wp-content\/uploads\/2021\/12\/logo.png\",\"width\":243,\"height\":59,\"caption\":\"Federassantas\"},\"image\":{\"@id\":\"https:\/\/www.federassantas.org.br\/novosite\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.federassantas.org.br\/novosite\/#\/schema\/person\/75fed98158349313fe56175f232f513c\",\"name\":\"admin-federas\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.federassantas.org.br\/novosite\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/2a02d7dda59fe8dc6b7ffd3f652e2efede5ccf0dd89dfdc8137c5517f3de8407?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/2a02d7dda59fe8dc6b7ffd3f652e2efede5ccf0dd89dfdc8137c5517f3de8407?s=96&d=mm&r=g\",\"caption\":\"admin-federas\"},\"sameAs\":[\"https:\/\/www.federassantas.org.br\/novosite\/\"],\"url\":\"https:\/\/www.federassantas.org.br\/novosite\/author\/admin-federas\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Neurocirurgi\u00e3o da Santa Casa de Montes Claros \u00e9 destaque em revista internacional norte-americana - Federassantas","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.federassantas.org.br\/novosite\/neurocirurgiao-da-santa-casa-de-montes-claros-e-destaque-em-revista-internacional-norte-americana\/","og_locale":"pt_BR","og_type":"article","og_title":"Neurocirurgi\u00e3o da Santa Casa de Montes Claros \u00e9 destaque em revista internacional norte-americana - Federassantas","og_description":"Neurocirurgi\u00e3o da Santa Casa de Montes Claros \u00e9 destaque em revista internacional norte-americana Neste m\u00eas de janeiro, o trabalho desenvolvido pelo neurocirurgi\u00e3o da Santa Casa Montes Claros, Dr. Lu\u00eds Gustavo Biondi, foi capa da revista internacional norte-americana OperativeNeurosurgery, que \u00e9 considerada uma das mais renomadas revistas de neurocirurgia do mundo, al\u00e9m de integrar o CNS [&hellip;]","og_url":"https:\/\/www.federassantas.org.br\/novosite\/neurocirurgiao-da-santa-casa-de-montes-claros-e-destaque-em-revista-internacional-norte-americana\/","og_site_name":"Federassantas","article_published_time":"2024-02-05T12:39:15+00:00","article_modified_time":"2024-02-05T12:40:54+00:00","og_image":[{"width":1920,"height":2560,"url":"https:\/\/www.federassantas.org.br\/novosite\/wp-content\/uploads\/2024\/02\/DR-BIONDI-2-scaled.jpg","type":"image\/jpeg"}],"author":"admin-federas","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"admin-federas","Est. tempo de leitura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.federassantas.org.br\/novosite\/neurocirurgiao-da-santa-casa-de-montes-claros-e-destaque-em-revista-internacional-norte-americana\/#article","isPartOf":{"@id":"https:\/\/www.federassantas.org.br\/novosite\/neurocirurgiao-da-santa-casa-de-montes-claros-e-destaque-em-revista-internacional-norte-americana\/"},"author":{"name":"admin-federas","@id":"https:\/\/www.federassantas.org.br\/novosite\/#\/schema\/person\/75fed98158349313fe56175f232f513c"},"headline":"Neurocirurgi\u00e3o da Santa Casa de Montes Claros \u00e9 destaque em revista internacional norte-americana","datePublished":"2024-02-05T12:39:15+00:00","dateModified":"2024-02-05T12:40:54+00:00","mainEntityOfPage":{"@id":"https:\/\/www.federassantas.org.br\/novosite\/neurocirurgiao-da-santa-casa-de-montes-claros-e-destaque-em-revista-internacional-norte-americana\/"},"wordCount":645,"commentCount":0,"publisher":{"@id":"https:\/\/www.federassantas.org.br\/novosite\/#organization"},"image":{"@id":"https:\/\/www.federassantas.org.br\/novosite\/neurocirurgiao-da-santa-casa-de-montes-claros-e-destaque-em-revista-internacional-norte-americana\/#primaryimage"},"thumbnailUrl":"https:\/\/www.federassantas.org.br\/novosite\/wp-content\/uploads\/2024\/02\/DR-BIONDI-2-scaled.jpg","keywords":["Destaque","neurocirurgi\u00e3o","Santa Casa Montes Claros"],"articleSection":["Not\u00edcias filiados","Regional Norte"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.federassantas.org.br\/novosite\/neurocirurgiao-da-santa-casa-de-montes-claros-e-destaque-em-revista-internacional-norte-americana\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.federassantas.org.br\/novosite\/neurocirurgiao-da-santa-casa-de-montes-claros-e-destaque-em-revista-internacional-norte-americana\/","url":"https:\/\/www.federassantas.org.br\/novosite\/neurocirurgiao-da-santa-casa-de-montes-claros-e-destaque-em-revista-internacional-norte-americana\/","name":"Neurocirurgi\u00e3o da Santa Casa de Montes Claros \u00e9 destaque em revista internacional norte-americana - Federassantas","isPartOf":{"@id":"https:\/\/www.federassantas.org.br\/novosite\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.federassantas.org.br\/novosite\/neurocirurgiao-da-santa-casa-de-montes-claros-e-destaque-em-revista-internacional-norte-americana\/#primaryimage"},"image":{"@id":"https:\/\/www.federassantas.org.br\/novosite\/neurocirurgiao-da-santa-casa-de-montes-claros-e-destaque-em-revista-internacional-norte-americana\/#primaryimage"},"thumbnailUrl":"https:\/\/www.federassantas.org.br\/novosite\/wp-content\/uploads\/2024\/02\/DR-BIONDI-2-scaled.jpg","datePublished":"2024-02-05T12:39:15+00:00","dateModified":"2024-02-05T12:40:54+00:00","breadcrumb":{"@id":"https:\/\/www.federassantas.org.br\/novosite\/neurocirurgiao-da-santa-casa-de-montes-claros-e-destaque-em-revista-internacional-norte-americana\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.federassantas.org.br\/novosite\/neurocirurgiao-da-santa-casa-de-montes-claros-e-destaque-em-revista-internacional-norte-americana\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.federassantas.org.br\/novosite\/neurocirurgiao-da-santa-casa-de-montes-claros-e-destaque-em-revista-internacional-norte-americana\/#primaryimage","url":"https:\/\/www.federassantas.org.br\/novosite\/wp-content\/uploads\/2024\/02\/DR-BIONDI-2-scaled.jpg","contentUrl":"https:\/\/www.federassantas.org.br\/novosite\/wp-content\/uploads\/2024\/02\/DR-BIONDI-2-scaled.jpg","width":1920,"height":2560},{"@type":"BreadcrumbList","@id":"https:\/\/www.federassantas.org.br\/novosite\/neurocirurgiao-da-santa-casa-de-montes-claros-e-destaque-em-revista-internacional-norte-americana\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/www.federassantas.org.br\/novosite\/"},{"@type":"ListItem","position":2,"name":"Neurocirurgi\u00e3o da Santa Casa de Montes Claros \u00e9 destaque em revista internacional norte-americana"}]},{"@type":"WebSite","@id":"https:\/\/www.federassantas.org.br\/novosite\/#website","url":"https:\/\/www.federassantas.org.br\/novosite\/","name":"Federassantas","description":"Entidade de representa\u00e7\u00e3o e fortalecimento das Santas Casas, hospitais filantr\u00f3picos e entidades beneficentes de sa\u00fade de Minas Gerais, atuando na defesa institucional, qualifica\u00e7\u00e3o da gest\u00e3o e sustentabilidade do setor.","publisher":{"@id":"https:\/\/www.federassantas.org.br\/novosite\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.federassantas.org.br\/novosite\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/www.federassantas.org.br\/novosite\/#organization","name":"Federassantas","url":"https:\/\/www.federassantas.org.br\/novosite\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.federassantas.org.br\/novosite\/#\/schema\/logo\/image\/","url":"https:\/\/www.federassantas.org.br\/novosite\/wp-content\/uploads\/2021\/12\/logo.png","contentUrl":"https:\/\/www.federassantas.org.br\/novosite\/wp-content\/uploads\/2021\/12\/logo.png","width":243,"height":59,"caption":"Federassantas"},"image":{"@id":"https:\/\/www.federassantas.org.br\/novosite\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.federassantas.org.br\/novosite\/#\/schema\/person\/75fed98158349313fe56175f232f513c","name":"admin-federas","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.federassantas.org.br\/novosite\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/2a02d7dda59fe8dc6b7ffd3f652e2efede5ccf0dd89dfdc8137c5517f3de8407?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/2a02d7dda59fe8dc6b7ffd3f652e2efede5ccf0dd89dfdc8137c5517f3de8407?s=96&d=mm&r=g","caption":"admin-federas"},"sameAs":["https:\/\/www.federassantas.org.br\/novosite\/"],"url":"https:\/\/www.federassantas.org.br\/novosite\/author\/admin-federas\/"}]}},"_links":{"self":[{"href":"https:\/\/www.federassantas.org.br\/novosite\/wp-json\/wp\/v2\/posts\/31403","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.federassantas.org.br\/novosite\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.federassantas.org.br\/novosite\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.federassantas.org.br\/novosite\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.federassantas.org.br\/novosite\/wp-json\/wp\/v2\/comments?post=31403"}],"version-history":[{"count":5,"href":"https:\/\/www.federassantas.org.br\/novosite\/wp-json\/wp\/v2\/posts\/31403\/revisions"}],"predecessor-version":[{"id":31410,"href":"https:\/\/www.federassantas.org.br\/novosite\/wp-json\/wp\/v2\/posts\/31403\/revisions\/31410"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.federassantas.org.br\/novosite\/wp-json\/wp\/v2\/media\/31405"}],"wp:attachment":[{"href":"https:\/\/www.federassantas.org.br\/novosite\/wp-json\/wp\/v2\/media?parent=31403"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.federassantas.org.br\/novosite\/wp-json\/wp\/v2\/categories?post=31403"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.federassantas.org.br\/novosite\/wp-json\/wp\/v2\/tags?post=31403"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}