{"id":31425,"date":"2024-02-05T10:21:12","date_gmt":"2024-02-05T13:21:12","guid":{"rendered":"https:\/\/www.federassantas.org.br\/novosite\/?p=31425"},"modified":"2024-02-05T10:24:07","modified_gmt":"2024-02-05T13:24:07","slug":"santa-casa-bh-recebe-certificacao-green-kitchen-pelo-quinto-ano-consecutivo","status":"publish","type":"post","link":"https:\/\/www.federassantas.org.br\/novosite\/santa-casa-bh-recebe-certificacao-green-kitchen-pelo-quinto-ano-consecutivo\/","title":{"rendered":"Santa Casa BH recebe certifica\u00e7\u00e3o Green Kitchen pelo quinto ano consecutivo"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"31425\" class=\"elementor elementor-31425\" data-elementor-post-type=\"post\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-e422a6b elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"e422a6b\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-86b194f\" data-id=\"86b194f\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-11dbd5f elementor-widget elementor-widget-heading\" data-id=\"11dbd5f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Santa Casa BH recebe certifica\u00e7\u00e3o Green Kitchen pelo quinto ano consecutivo \n<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-605b20c elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"605b20c\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-fe7a0b4\" data-id=\"fe7a0b4\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6826bfd elementor-widget elementor-widget-text-editor\" data-id=\"6826bfd\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p dir=\"ltr\">Selo reconhece&nbsp;as pr\u00e1ticas ambientalmente corretas na produ\u00e7\u00e3o di\u00e1ria de mais de 10 mil na institui\u00e7\u00e3o&nbsp;<\/p>\n<p><\/p>\n<p dir=\"ltr\">Em mais um reconhecimento do seu compromisso com a excel\u00eancia e a sustentabilidade, a Santa Casa BH acaba de conquistar, pelo quinto ano consecutivo, a certifica\u00e7\u00e3o Green Kitchen, destinada aos estabelecimentos com as maiores pontua\u00e7\u00f5es em cozinhas sustent\u00e1veis. O selo \u00e9 fruto do trabalho desenvolvido pelo Servi\u00e7o de Nutri\u00e7\u00e3o e Diet\u00e9tica (SND), em parceria com o setor de Meio Ambiente e Sustentabilidade e a \u00e1rea de Hotelaria e Facilities.<\/p>\n<p dir=\"ltr\">Criado pela Funda\u00e7\u00e3o para a Pesquisa em Arquitetura e Ambiente (Fupam), o Green Kitchen atesta, mais uma vez, as pr\u00e1ticas ambientalmente corretas da Santa Casa BH na produ\u00e7\u00e3o das mais de 10 mil refei\u00e7\u00f5es distribu\u00eddas diariamente para seus pacientes e acompanhantes. A gerente do SND, Vanessa Andrade, explica que o foco na alta qualidade e na inova\u00e7\u00e3o \u00e9 crucial para esse resultado.&nbsp;<\/p>\n<p dir=\"ltr\">\u201cUm dos pilares fundamentais no preparo do card\u00e1pio \u00e9 a utiliza\u00e7\u00e3o exclusiva de temperos naturais org\u00e2nicos, proporcionando n\u00e3o apenas sabores aut\u00eanticos, mas tamb\u00e9m promovendo a sa\u00fade, por meio de escolhas alimentares conscientes. A integralidade na utiliza\u00e7\u00e3o dos alimentos \u00e9 outra marca registrada da nossa cozinha. Cada ingrediente \u00e9 valorizado em sua totalidade, reduzindo significativamente os desperd\u00edcios e contribuindo para um modelo de produ\u00e7\u00e3o mais eficiente e respons\u00e1vel\u201d, conta a gerente.&nbsp;<\/p>\n<p dir=\"ltr\">Para alcan\u00e7ar essas pr\u00e1ticas, Vanessa explica que, nos bastidores, os profissionais envolvidos recebem orienta\u00e7\u00f5es direcionadas para um uso consciente de recursos, desde a escolha de produtos de limpeza biodegrad\u00e1veis at\u00e9 controles rigorosos da qualidade da \u00e1gua e das instala\u00e7\u00f5es.&nbsp;<\/p>\n<p dir=\"ltr\">\u201cO compromisso n\u00e3o se limita \u00e0 cozinha, se estende a uma gest\u00e3o exemplar dos res\u00edduos, fomentando a\u00e7\u00f5es que impulsionam a educa\u00e7\u00e3o ambiental e promovem a conscientiza\u00e7\u00e3o sobre a import\u00e2ncia de preservar nosso planeta\u201d, ressalta.&nbsp;<\/p>\n<p dir=\"ltr\">Vanessa finaliza destacando que o trabalho desenvolvido pelo Servi\u00e7o de Nutri\u00e7\u00e3o e Diet\u00e9tica \u00e9 de fundamental import\u00e2ncia para a assist\u00eancia aos pacientes \u201cOferecer sa\u00fade de ponta para todos passa, obrigatoriamente, pela nutri\u00e7\u00e3o deles. Nesse sentido, cada um possui uma dieta seguida \u00e0 risca e isso \u00e9 primordial para a sua completa recupera\u00e7\u00e3o. Essa conquista vem coroar esse trabalho, que \u00e9 realizado por muitas m\u00e3os todos os dias\u201d, completou a gerente.&nbsp;<\/p>\n<p dir=\"ltr\">Assessoria de Imprensa: Laio Amaral<\/p><p dir=\"ltr\"><em style=\"color: var( --e-global-color-text ); font-size: 0.9rem;\">Gostaria de divulgar informa\u00e7\u00f5es do seu hospital no site da Federassantas? Acesse a&nbsp;<a href=\"https:\/\/www.federassantas.org.br\/novosite\/comunicacao\/\">p\u00e1gina da comunica\u00e7\u00e3o<\/a>&nbsp;e nos envie o seu release.<\/em><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Santa Casa BH recebe certifica\u00e7\u00e3o Green Kitchen pelo quinto ano consecutivo Selo reconhece&nbsp;as pr\u00e1ticas ambientalmente corretas na produ\u00e7\u00e3o di\u00e1ria de mais de 10 mil na institui\u00e7\u00e3o&nbsp; Em mais um reconhecimento do seu compromisso com a excel\u00eancia e a sustentabilidade, a Santa Casa BH acaba de conquistar, pelo quinto ano consecutivo, a certifica\u00e7\u00e3o Green Kitchen, destinada [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":31426,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[139],"tags":[713,714,270],"class_list":["post-31425","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias-filiados","tag-certificacao","tag-green-kitchen","tag-santa-casa-bh"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Santa Casa BH recebe certifica\u00e7\u00e3o Green Kitchen pelo quinto ano consecutivo - Federassantas<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.federassantas.org.br\/novosite\/santa-casa-bh-recebe-certificacao-green-kitchen-pelo-quinto-ano-consecutivo\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Santa Casa BH recebe certifica\u00e7\u00e3o Green Kitchen pelo quinto ano consecutivo - Federassantas\" \/>\n<meta property=\"og:description\" content=\"Santa Casa BH recebe certifica\u00e7\u00e3o Green Kitchen pelo quinto ano consecutivo Selo reconhece&nbsp;as pr\u00e1ticas ambientalmente corretas na produ\u00e7\u00e3o di\u00e1ria de mais de 10 mil na institui\u00e7\u00e3o&nbsp; Em mais um reconhecimento do seu compromisso com a excel\u00eancia e a sustentabilidade, a Santa Casa BH acaba de conquistar, pelo quinto ano consecutivo, a certifica\u00e7\u00e3o Green Kitchen, destinada [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.federassantas.org.br\/novosite\/santa-casa-bh-recebe-certificacao-green-kitchen-pelo-quinto-ano-consecutivo\/\" \/>\n<meta property=\"og:site_name\" content=\"Federassantas\" \/>\n<meta property=\"article:published_time\" content=\"2024-02-05T13:21:12+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-02-05T13:24:07+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.federassantas.org.br\/novosite\/wp-content\/uploads\/2024\/02\/Divulgacao-Santa-Casa-BH.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"960\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"admin-federas\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin-federas\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.federassantas.org.br\/novosite\/santa-casa-bh-recebe-certificacao-green-kitchen-pelo-quinto-ano-consecutivo\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.federassantas.org.br\/novosite\/santa-casa-bh-recebe-certificacao-green-kitchen-pelo-quinto-ano-consecutivo\/\"},\"author\":{\"name\":\"admin-federas\",\"@id\":\"https:\/\/www.federassantas.org.br\/novosite\/#\/schema\/person\/75fed98158349313fe56175f232f513c\"},\"headline\":\"Santa Casa BH recebe certifica\u00e7\u00e3o Green Kitchen pelo quinto ano consecutivo\",\"datePublished\":\"2024-02-05T13:21:12+00:00\",\"dateModified\":\"2024-02-05T13:24:07+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.federassantas.org.br\/novosite\/santa-casa-bh-recebe-certificacao-green-kitchen-pelo-quinto-ano-consecutivo\/\"},\"wordCount\":460,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/www.federassantas.org.br\/novosite\/#organization\"},\"image\":{\"@id\":\"https:\/\/www.federassantas.org.br\/novosite\/santa-casa-bh-recebe-certificacao-green-kitchen-pelo-quinto-ano-consecutivo\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.federassantas.org.br\/novosite\/wp-content\/uploads\/2024\/02\/Divulgacao-Santa-Casa-BH.jpeg\",\"keywords\":[\"certifica\u00e7\u00e3o\",\"Green Kitchen\",\"Santa Casa BH\"],\"articleSection\":[\"Not\u00edcias filiados\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/www.federassantas.org.br\/novosite\/santa-casa-bh-recebe-certificacao-green-kitchen-pelo-quinto-ano-consecutivo\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.federassantas.org.br\/novosite\/santa-casa-bh-recebe-certificacao-green-kitchen-pelo-quinto-ano-consecutivo\/\",\"url\":\"https:\/\/www.federassantas.org.br\/novosite\/santa-casa-bh-recebe-certificacao-green-kitchen-pelo-quinto-ano-consecutivo\/\",\"name\":\"Santa Casa BH recebe certifica\u00e7\u00e3o Green Kitchen pelo quinto ano consecutivo - Federassantas\",\"isPartOf\":{\"@id\":\"https:\/\/www.federassantas.org.br\/novosite\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.federassantas.org.br\/novosite\/santa-casa-bh-recebe-certificacao-green-kitchen-pelo-quinto-ano-consecutivo\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.federassantas.org.br\/novosite\/santa-casa-bh-recebe-certificacao-green-kitchen-pelo-quinto-ano-consecutivo\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.federassantas.org.br\/novosite\/wp-content\/uploads\/2024\/02\/Divulgacao-Santa-Casa-BH.jpeg\",\"datePublished\":\"2024-02-05T13:21:12+00:00\",\"dateModified\":\"2024-02-05T13:24:07+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.federassantas.org.br\/novosite\/santa-casa-bh-recebe-certificacao-green-kitchen-pelo-quinto-ano-consecutivo\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.federassantas.org.br\/novosite\/santa-casa-bh-recebe-certificacao-green-kitchen-pelo-quinto-ano-consecutivo\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.federassantas.org.br\/novosite\/santa-casa-bh-recebe-certificacao-green-kitchen-pelo-quinto-ano-consecutivo\/#primaryimage\",\"url\":\"https:\/\/www.federassantas.org.br\/novosite\/wp-content\/uploads\/2024\/02\/Divulgacao-Santa-Casa-BH.jpeg\",\"contentUrl\":\"https:\/\/www.federassantas.org.br\/novosite\/wp-content\/uploads\/2024\/02\/Divulgacao-Santa-Casa-BH.jpeg\",\"width\":1280,\"height\":960},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.federassantas.org.br\/novosite\/santa-casa-bh-recebe-certificacao-green-kitchen-pelo-quinto-ano-consecutivo\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/www.federassantas.org.br\/novosite\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Santa Casa BH recebe certifica\u00e7\u00e3o Green Kitchen pelo quinto ano consecutivo\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.federassantas.org.br\/novosite\/#website\",\"url\":\"https:\/\/www.federassantas.org.br\/novosite\/\",\"name\":\"Federassantas\",\"description\":\"Entidade de representa\u00e7\u00e3o e fortalecimento das Santas Casas, hospitais filantr\u00f3picos e entidades beneficentes de sa\u00fade de Minas Gerais, atuando na defesa institucional, qualifica\u00e7\u00e3o da gest\u00e3o e sustentabilidade do setor.\",\"publisher\":{\"@id\":\"https:\/\/www.federassantas.org.br\/novosite\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.federassantas.org.br\/novosite\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.federassantas.org.br\/novosite\/#organization\",\"name\":\"Federassantas\",\"url\":\"https:\/\/www.federassantas.org.br\/novosite\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.federassantas.org.br\/novosite\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.federassantas.org.br\/novosite\/wp-content\/uploads\/2021\/12\/logo.png\",\"contentUrl\":\"https:\/\/www.federassantas.org.br\/novosite\/wp-content\/uploads\/2021\/12\/logo.png\",\"width\":243,\"height\":59,\"caption\":\"Federassantas\"},\"image\":{\"@id\":\"https:\/\/www.federassantas.org.br\/novosite\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.federassantas.org.br\/novosite\/#\/schema\/person\/75fed98158349313fe56175f232f513c\",\"name\":\"admin-federas\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.federassantas.org.br\/novosite\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/2a02d7dda59fe8dc6b7ffd3f652e2efede5ccf0dd89dfdc8137c5517f3de8407?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/2a02d7dda59fe8dc6b7ffd3f652e2efede5ccf0dd89dfdc8137c5517f3de8407?s=96&d=mm&r=g\",\"caption\":\"admin-federas\"},\"sameAs\":[\"https:\/\/www.federassantas.org.br\/novosite\/\"],\"url\":\"https:\/\/www.federassantas.org.br\/novosite\/author\/admin-federas\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Santa Casa BH recebe certifica\u00e7\u00e3o Green Kitchen pelo quinto ano consecutivo - Federassantas","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.federassantas.org.br\/novosite\/santa-casa-bh-recebe-certificacao-green-kitchen-pelo-quinto-ano-consecutivo\/","og_locale":"pt_BR","og_type":"article","og_title":"Santa Casa BH recebe certifica\u00e7\u00e3o Green Kitchen pelo quinto ano consecutivo - Federassantas","og_description":"Santa Casa BH recebe certifica\u00e7\u00e3o Green Kitchen pelo quinto ano consecutivo Selo reconhece&nbsp;as pr\u00e1ticas ambientalmente corretas na produ\u00e7\u00e3o di\u00e1ria de mais de 10 mil na institui\u00e7\u00e3o&nbsp; Em mais um reconhecimento do seu compromisso com a excel\u00eancia e a sustentabilidade, a Santa Casa BH acaba de conquistar, pelo quinto ano consecutivo, a certifica\u00e7\u00e3o Green Kitchen, destinada [&hellip;]","og_url":"https:\/\/www.federassantas.org.br\/novosite\/santa-casa-bh-recebe-certificacao-green-kitchen-pelo-quinto-ano-consecutivo\/","og_site_name":"Federassantas","article_published_time":"2024-02-05T13:21:12+00:00","article_modified_time":"2024-02-05T13:24:07+00:00","og_image":[{"width":1280,"height":960,"url":"https:\/\/www.federassantas.org.br\/novosite\/wp-content\/uploads\/2024\/02\/Divulgacao-Santa-Casa-BH.jpeg","type":"image\/jpeg"}],"author":"admin-federas","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"admin-federas","Est. tempo de leitura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.federassantas.org.br\/novosite\/santa-casa-bh-recebe-certificacao-green-kitchen-pelo-quinto-ano-consecutivo\/#article","isPartOf":{"@id":"https:\/\/www.federassantas.org.br\/novosite\/santa-casa-bh-recebe-certificacao-green-kitchen-pelo-quinto-ano-consecutivo\/"},"author":{"name":"admin-federas","@id":"https:\/\/www.federassantas.org.br\/novosite\/#\/schema\/person\/75fed98158349313fe56175f232f513c"},"headline":"Santa Casa BH recebe certifica\u00e7\u00e3o Green Kitchen pelo quinto ano consecutivo","datePublished":"2024-02-05T13:21:12+00:00","dateModified":"2024-02-05T13:24:07+00:00","mainEntityOfPage":{"@id":"https:\/\/www.federassantas.org.br\/novosite\/santa-casa-bh-recebe-certificacao-green-kitchen-pelo-quinto-ano-consecutivo\/"},"wordCount":460,"commentCount":0,"publisher":{"@id":"https:\/\/www.federassantas.org.br\/novosite\/#organization"},"image":{"@id":"https:\/\/www.federassantas.org.br\/novosite\/santa-casa-bh-recebe-certificacao-green-kitchen-pelo-quinto-ano-consecutivo\/#primaryimage"},"thumbnailUrl":"https:\/\/www.federassantas.org.br\/novosite\/wp-content\/uploads\/2024\/02\/Divulgacao-Santa-Casa-BH.jpeg","keywords":["certifica\u00e7\u00e3o","Green Kitchen","Santa Casa BH"],"articleSection":["Not\u00edcias filiados"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.federassantas.org.br\/novosite\/santa-casa-bh-recebe-certificacao-green-kitchen-pelo-quinto-ano-consecutivo\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.federassantas.org.br\/novosite\/santa-casa-bh-recebe-certificacao-green-kitchen-pelo-quinto-ano-consecutivo\/","url":"https:\/\/www.federassantas.org.br\/novosite\/santa-casa-bh-recebe-certificacao-green-kitchen-pelo-quinto-ano-consecutivo\/","name":"Santa Casa BH recebe certifica\u00e7\u00e3o Green Kitchen pelo quinto ano consecutivo - Federassantas","isPartOf":{"@id":"https:\/\/www.federassantas.org.br\/novosite\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.federassantas.org.br\/novosite\/santa-casa-bh-recebe-certificacao-green-kitchen-pelo-quinto-ano-consecutivo\/#primaryimage"},"image":{"@id":"https:\/\/www.federassantas.org.br\/novosite\/santa-casa-bh-recebe-certificacao-green-kitchen-pelo-quinto-ano-consecutivo\/#primaryimage"},"thumbnailUrl":"https:\/\/www.federassantas.org.br\/novosite\/wp-content\/uploads\/2024\/02\/Divulgacao-Santa-Casa-BH.jpeg","datePublished":"2024-02-05T13:21:12+00:00","dateModified":"2024-02-05T13:24:07+00:00","breadcrumb":{"@id":"https:\/\/www.federassantas.org.br\/novosite\/santa-casa-bh-recebe-certificacao-green-kitchen-pelo-quinto-ano-consecutivo\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.federassantas.org.br\/novosite\/santa-casa-bh-recebe-certificacao-green-kitchen-pelo-quinto-ano-consecutivo\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.federassantas.org.br\/novosite\/santa-casa-bh-recebe-certificacao-green-kitchen-pelo-quinto-ano-consecutivo\/#primaryimage","url":"https:\/\/www.federassantas.org.br\/novosite\/wp-content\/uploads\/2024\/02\/Divulgacao-Santa-Casa-BH.jpeg","contentUrl":"https:\/\/www.federassantas.org.br\/novosite\/wp-content\/uploads\/2024\/02\/Divulgacao-Santa-Casa-BH.jpeg","width":1280,"height":960},{"@type":"BreadcrumbList","@id":"https:\/\/www.federassantas.org.br\/novosite\/santa-casa-bh-recebe-certificacao-green-kitchen-pelo-quinto-ano-consecutivo\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/www.federassantas.org.br\/novosite\/"},{"@type":"ListItem","position":2,"name":"Santa Casa BH recebe certifica\u00e7\u00e3o Green Kitchen pelo quinto ano consecutivo"}]},{"@type":"WebSite","@id":"https:\/\/www.federassantas.org.br\/novosite\/#website","url":"https:\/\/www.federassantas.org.br\/novosite\/","name":"Federassantas","description":"Entidade de representa\u00e7\u00e3o e fortalecimento das Santas Casas, hospitais filantr\u00f3picos e entidades beneficentes de sa\u00fade de Minas Gerais, atuando na defesa institucional, qualifica\u00e7\u00e3o da gest\u00e3o e sustentabilidade do setor.","publisher":{"@id":"https:\/\/www.federassantas.org.br\/novosite\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.federassantas.org.br\/novosite\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/www.federassantas.org.br\/novosite\/#organization","name":"Federassantas","url":"https:\/\/www.federassantas.org.br\/novosite\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.federassantas.org.br\/novosite\/#\/schema\/logo\/image\/","url":"https:\/\/www.federassantas.org.br\/novosite\/wp-content\/uploads\/2021\/12\/logo.png","contentUrl":"https:\/\/www.federassantas.org.br\/novosite\/wp-content\/uploads\/2021\/12\/logo.png","width":243,"height":59,"caption":"Federassantas"},"image":{"@id":"https:\/\/www.federassantas.org.br\/novosite\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.federassantas.org.br\/novosite\/#\/schema\/person\/75fed98158349313fe56175f232f513c","name":"admin-federas","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.federassantas.org.br\/novosite\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/2a02d7dda59fe8dc6b7ffd3f652e2efede5ccf0dd89dfdc8137c5517f3de8407?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/2a02d7dda59fe8dc6b7ffd3f652e2efede5ccf0dd89dfdc8137c5517f3de8407?s=96&d=mm&r=g","caption":"admin-federas"},"sameAs":["https:\/\/www.federassantas.org.br\/novosite\/"],"url":"https:\/\/www.federassantas.org.br\/novosite\/author\/admin-federas\/"}]}},"_links":{"self":[{"href":"https:\/\/www.federassantas.org.br\/novosite\/wp-json\/wp\/v2\/posts\/31425","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.federassantas.org.br\/novosite\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.federassantas.org.br\/novosite\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.federassantas.org.br\/novosite\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.federassantas.org.br\/novosite\/wp-json\/wp\/v2\/comments?post=31425"}],"version-history":[{"count":4,"href":"https:\/\/www.federassantas.org.br\/novosite\/wp-json\/wp\/v2\/posts\/31425\/revisions"}],"predecessor-version":[{"id":31430,"href":"https:\/\/www.federassantas.org.br\/novosite\/wp-json\/wp\/v2\/posts\/31425\/revisions\/31430"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.federassantas.org.br\/novosite\/wp-json\/wp\/v2\/media\/31426"}],"wp:attachment":[{"href":"https:\/\/www.federassantas.org.br\/novosite\/wp-json\/wp\/v2\/media?parent=31425"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.federassantas.org.br\/novosite\/wp-json\/wp\/v2\/categories?post=31425"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.federassantas.org.br\/novosite\/wp-json\/wp\/v2\/tags?post=31425"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}