{"id":31470,"date":"2024-02-08T09:52:00","date_gmt":"2024-02-08T12:52:00","guid":{"rendered":"https:\/\/www.federassantas.org.br\/novosite\/?p=31470"},"modified":"2024-02-08T09:54:55","modified_gmt":"2024-02-08T12:54:55","slug":"santa-casa-de-alfenas-realiza-mamografia-em-mulheres-atendidas-pelos-grupos-de-estrategia-de-saude-da-familia-da-cidade-de-alterosa","status":"publish","type":"post","link":"https:\/\/www.federassantas.org.br\/novosite\/santa-casa-de-alfenas-realiza-mamografia-em-mulheres-atendidas-pelos-grupos-de-estrategia-de-saude-da-familia-da-cidade-de-alterosa\/","title":{"rendered":"Santa Casa de Alfenas realiza mamografia em mulheres atendidas pelos grupos de Estrat\u00e9gia de Sa\u00fade da Fam\u00edlia da cidade de Alterosa"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"31470\" class=\"elementor elementor-31470\" data-elementor-post-type=\"post\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-83c3811 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"83c3811\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-1960c3c\" data-id=\"1960c3c\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3aee83f elementor-widget elementor-widget-heading\" data-id=\"3aee83f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Santa Casa de Alfenas realiza mamografia em mulheres atendidas pelos grupos de Estrat\u00e9gia de Sa\u00fade da Fam\u00edlia da cidade de Alterosa\n<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-1a81143 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"1a81143\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-e63e94c\" data-id=\"e63e94c\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6cf6e49 elementor-widget elementor-widget-text-editor\" data-id=\"6cf6e49\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Equipada com mam\u00f3grafo de \u00faltima gera\u00e7\u00e3o, a Santa Casa de Alfenas recebeu no \u00faltimo s\u00e1bado (03\/02) para a realiza\u00e7\u00e3o de mamografias as mulheres atendidas pelo ESF Cruzeiro, ESF Soraya e ESF Silveira da cidade de Alterosa. A oportunidade, concedida pela Secretaria Municipal de Sa\u00fade, foi muito bem acolhida pela comunidade.<\/p><p>As mulheres atendidas relataram tranquilidade e comodidade para realizar o exame, j\u00e1 que muitas evitam o procedimento com medo de algum desconforto ou dor.<\/p><p>No pr\u00f3ximo dia 17 de fevereiro, a iniciativa se estender\u00e1 \u00e0s pacientes do ESF Cavacos e do ESF Juarina. A partir desse ponto, est\u00e1 prevista a realiza\u00e7\u00e3o mensal de mamografias, com o sistema de mutir\u00e3o, o que facilita o acesso a esse exame vital.<\/p><p>A entrega dos resultados est\u00e1 programada para o dia 20 de fevereiro, tal a\u00e7\u00e3o contribui para a agilidade e efici\u00eancia no diagn\u00f3stico e tratamento, se necess\u00e1rio. Este esfor\u00e7o cont\u00ednuo visa promover a sa\u00fade e o bem-estar das mulheres da comunidade e refor\u00e7a a import\u00e2ncia da preven\u00e7\u00e3o e do acompanhamento m\u00e9dico regular.<\/p><p><em style=\"color: var( --e-global-color-text ); font-size: 0.9rem;\">Gostaria de divulgar informa\u00e7\u00f5es do seu hospital no site da Federassantas? Acesse a\u00a0<a href=\"https:\/\/www.federassantas.org.br\/novosite\/comunicacao\/\">p\u00e1gina da comunica\u00e7\u00e3o<\/a>\u00a0e nos envie o seu release.<\/em><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5f80580 elementor-widget__width-initial elementor-widget elementor-widget-image\" data-id=\"5f80580\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"800\" height=\"444\" src=\"https:\/\/www.federassantas.org.br\/novosite\/wp-content\/uploads\/2024\/02\/WhatsApp-Image-2024-02-08-at-09.51.26.jpeg\" class=\"attachment-large size-large wp-image-31473\" alt=\"\" srcset=\"https:\/\/www.federassantas.org.br\/novosite\/wp-content\/uploads\/2024\/02\/WhatsApp-Image-2024-02-08-at-09.51.26.jpeg 828w, https:\/\/www.federassantas.org.br\/novosite\/wp-content\/uploads\/2024\/02\/WhatsApp-Image-2024-02-08-at-09.51.26-300x167.jpeg 300w, https:\/\/www.federassantas.org.br\/novosite\/wp-content\/uploads\/2024\/02\/WhatsApp-Image-2024-02-08-at-09.51.26-768x427.jpeg 768w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Santa Casa de Alfenas realiza mamografia em mulheres atendidas pelos grupos de Estrat\u00e9gia de Sa\u00fade da Fam\u00edlia da cidade de Alterosa Equipada com mam\u00f3grafo de \u00faltima gera\u00e7\u00e3o, a Santa Casa de Alfenas recebeu no \u00faltimo s\u00e1bado (03\/02) para a realiza\u00e7\u00e3o de mamografias as mulheres atendidas pelo ESF Cruzeiro, ESF Soraya e ESF Silveira da cidade [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":31471,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[139,243,250],"tags":[722,723,721],"class_list":["post-31470","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias-filiados","category-regionais","category-regional-sul","tag-alterosa","tag-mamografia","tag-santa-casa-de-alfenas"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Santa Casa de Alfenas realiza mamografia em mulheres atendidas pelos grupos de Estrat\u00e9gia de Sa\u00fade da Fam\u00edlia da cidade de Alterosa - Federassantas<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.federassantas.org.br\/novosite\/santa-casa-de-alfenas-realiza-mamografia-em-mulheres-atendidas-pelos-grupos-de-estrategia-de-saude-da-familia-da-cidade-de-alterosa\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Santa Casa de Alfenas realiza mamografia em mulheres atendidas pelos grupos de Estrat\u00e9gia de Sa\u00fade da Fam\u00edlia da cidade de Alterosa - Federassantas\" \/>\n<meta property=\"og:description\" content=\"Santa Casa de Alfenas realiza mamografia em mulheres atendidas pelos grupos de Estrat\u00e9gia de Sa\u00fade da Fam\u00edlia da cidade de Alterosa Equipada com mam\u00f3grafo de \u00faltima gera\u00e7\u00e3o, a Santa Casa de Alfenas recebeu no \u00faltimo s\u00e1bado (03\/02) para a realiza\u00e7\u00e3o de mamografias as mulheres atendidas pelo ESF Cruzeiro, ESF Soraya e ESF Silveira da cidade [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.federassantas.org.br\/novosite\/santa-casa-de-alfenas-realiza-mamografia-em-mulheres-atendidas-pelos-grupos-de-estrategia-de-saude-da-familia-da-cidade-de-alterosa\/\" \/>\n<meta property=\"og:site_name\" content=\"Federassantas\" \/>\n<meta property=\"article:published_time\" content=\"2024-02-08T12:52:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-02-08T12:54:55+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.federassantas.org.br\/novosite\/wp-content\/uploads\/2024\/02\/WhatsApp-Image-2024-02-08-at-09.51.24.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"828\" \/>\n\t<meta property=\"og:image:height\" content=\"454\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"admin-federas\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin-federas\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.federassantas.org.br\/novosite\/santa-casa-de-alfenas-realiza-mamografia-em-mulheres-atendidas-pelos-grupos-de-estrategia-de-saude-da-familia-da-cidade-de-alterosa\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.federassantas.org.br\/novosite\/santa-casa-de-alfenas-realiza-mamografia-em-mulheres-atendidas-pelos-grupos-de-estrategia-de-saude-da-familia-da-cidade-de-alterosa\/\"},\"author\":{\"name\":\"admin-federas\",\"@id\":\"https:\/\/www.federassantas.org.br\/novosite\/#\/schema\/person\/75fed98158349313fe56175f232f513c\"},\"headline\":\"Santa Casa de Alfenas realiza mamografia em mulheres atendidas pelos grupos de Estrat\u00e9gia de Sa\u00fade da Fam\u00edlia da cidade de Alterosa\",\"datePublished\":\"2024-02-08T12:52:00+00:00\",\"dateModified\":\"2024-02-08T12:54:55+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.federassantas.org.br\/novosite\/santa-casa-de-alfenas-realiza-mamografia-em-mulheres-atendidas-pelos-grupos-de-estrategia-de-saude-da-familia-da-cidade-de-alterosa\/\"},\"wordCount\":258,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/www.federassantas.org.br\/novosite\/#organization\"},\"image\":{\"@id\":\"https:\/\/www.federassantas.org.br\/novosite\/santa-casa-de-alfenas-realiza-mamografia-em-mulheres-atendidas-pelos-grupos-de-estrategia-de-saude-da-familia-da-cidade-de-alterosa\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.federassantas.org.br\/novosite\/wp-content\/uploads\/2024\/02\/WhatsApp-Image-2024-02-08-at-09.51.24.jpeg\",\"keywords\":[\"Alterosa\",\"mamografia\",\"Santa Casa de Alfenas\"],\"articleSection\":[\"Not\u00edcias filiados\",\"Regionais\",\"Regional Sul\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/www.federassantas.org.br\/novosite\/santa-casa-de-alfenas-realiza-mamografia-em-mulheres-atendidas-pelos-grupos-de-estrategia-de-saude-da-familia-da-cidade-de-alterosa\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.federassantas.org.br\/novosite\/santa-casa-de-alfenas-realiza-mamografia-em-mulheres-atendidas-pelos-grupos-de-estrategia-de-saude-da-familia-da-cidade-de-alterosa\/\",\"url\":\"https:\/\/www.federassantas.org.br\/novosite\/santa-casa-de-alfenas-realiza-mamografia-em-mulheres-atendidas-pelos-grupos-de-estrategia-de-saude-da-familia-da-cidade-de-alterosa\/\",\"name\":\"Santa Casa de Alfenas realiza mamografia em mulheres atendidas pelos grupos de Estrat\u00e9gia de Sa\u00fade da Fam\u00edlia da cidade de Alterosa - Federassantas\",\"isPartOf\":{\"@id\":\"https:\/\/www.federassantas.org.br\/novosite\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.federassantas.org.br\/novosite\/santa-casa-de-alfenas-realiza-mamografia-em-mulheres-atendidas-pelos-grupos-de-estrategia-de-saude-da-familia-da-cidade-de-alterosa\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.federassantas.org.br\/novosite\/santa-casa-de-alfenas-realiza-mamografia-em-mulheres-atendidas-pelos-grupos-de-estrategia-de-saude-da-familia-da-cidade-de-alterosa\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.federassantas.org.br\/novosite\/wp-content\/uploads\/2024\/02\/WhatsApp-Image-2024-02-08-at-09.51.24.jpeg\",\"datePublished\":\"2024-02-08T12:52:00+00:00\",\"dateModified\":\"2024-02-08T12:54:55+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.federassantas.org.br\/novosite\/santa-casa-de-alfenas-realiza-mamografia-em-mulheres-atendidas-pelos-grupos-de-estrategia-de-saude-da-familia-da-cidade-de-alterosa\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.federassantas.org.br\/novosite\/santa-casa-de-alfenas-realiza-mamografia-em-mulheres-atendidas-pelos-grupos-de-estrategia-de-saude-da-familia-da-cidade-de-alterosa\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.federassantas.org.br\/novosite\/santa-casa-de-alfenas-realiza-mamografia-em-mulheres-atendidas-pelos-grupos-de-estrategia-de-saude-da-familia-da-cidade-de-alterosa\/#primaryimage\",\"url\":\"https:\/\/www.federassantas.org.br\/novosite\/wp-content\/uploads\/2024\/02\/WhatsApp-Image-2024-02-08-at-09.51.24.jpeg\",\"contentUrl\":\"https:\/\/www.federassantas.org.br\/novosite\/wp-content\/uploads\/2024\/02\/WhatsApp-Image-2024-02-08-at-09.51.24.jpeg\",\"width\":828,\"height\":454},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.federassantas.org.br\/novosite\/santa-casa-de-alfenas-realiza-mamografia-em-mulheres-atendidas-pelos-grupos-de-estrategia-de-saude-da-familia-da-cidade-de-alterosa\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/www.federassantas.org.br\/novosite\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Santa Casa de Alfenas realiza mamografia em mulheres atendidas pelos grupos de Estrat\u00e9gia de Sa\u00fade da Fam\u00edlia da cidade de Alterosa\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.federassantas.org.br\/novosite\/#website\",\"url\":\"https:\/\/www.federassantas.org.br\/novosite\/\",\"name\":\"Federassantas\",\"description\":\"Entidade de representa\u00e7\u00e3o e fortalecimento das Santas Casas, hospitais filantr\u00f3picos e entidades beneficentes de sa\u00fade de Minas Gerais, atuando na defesa institucional, qualifica\u00e7\u00e3o da gest\u00e3o e sustentabilidade do setor.\",\"publisher\":{\"@id\":\"https:\/\/www.federassantas.org.br\/novosite\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.federassantas.org.br\/novosite\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.federassantas.org.br\/novosite\/#organization\",\"name\":\"Federassantas\",\"url\":\"https:\/\/www.federassantas.org.br\/novosite\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.federassantas.org.br\/novosite\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.federassantas.org.br\/novosite\/wp-content\/uploads\/2021\/12\/logo.png\",\"contentUrl\":\"https:\/\/www.federassantas.org.br\/novosite\/wp-content\/uploads\/2021\/12\/logo.png\",\"width\":243,\"height\":59,\"caption\":\"Federassantas\"},\"image\":{\"@id\":\"https:\/\/www.federassantas.org.br\/novosite\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.federassantas.org.br\/novosite\/#\/schema\/person\/75fed98158349313fe56175f232f513c\",\"name\":\"admin-federas\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.federassantas.org.br\/novosite\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/2a02d7dda59fe8dc6b7ffd3f652e2efede5ccf0dd89dfdc8137c5517f3de8407?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/2a02d7dda59fe8dc6b7ffd3f652e2efede5ccf0dd89dfdc8137c5517f3de8407?s=96&d=mm&r=g\",\"caption\":\"admin-federas\"},\"sameAs\":[\"https:\/\/www.federassantas.org.br\/novosite\/\"],\"url\":\"https:\/\/www.federassantas.org.br\/novosite\/author\/admin-federas\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Santa Casa de Alfenas realiza mamografia em mulheres atendidas pelos grupos de Estrat\u00e9gia de Sa\u00fade da Fam\u00edlia da cidade de Alterosa - Federassantas","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.federassantas.org.br\/novosite\/santa-casa-de-alfenas-realiza-mamografia-em-mulheres-atendidas-pelos-grupos-de-estrategia-de-saude-da-familia-da-cidade-de-alterosa\/","og_locale":"pt_BR","og_type":"article","og_title":"Santa Casa de Alfenas realiza mamografia em mulheres atendidas pelos grupos de Estrat\u00e9gia de Sa\u00fade da Fam\u00edlia da cidade de Alterosa - Federassantas","og_description":"Santa Casa de Alfenas realiza mamografia em mulheres atendidas pelos grupos de Estrat\u00e9gia de Sa\u00fade da Fam\u00edlia da cidade de Alterosa Equipada com mam\u00f3grafo de \u00faltima gera\u00e7\u00e3o, a Santa Casa de Alfenas recebeu no \u00faltimo s\u00e1bado (03\/02) para a realiza\u00e7\u00e3o de mamografias as mulheres atendidas pelo ESF Cruzeiro, ESF Soraya e ESF Silveira da cidade [&hellip;]","og_url":"https:\/\/www.federassantas.org.br\/novosite\/santa-casa-de-alfenas-realiza-mamografia-em-mulheres-atendidas-pelos-grupos-de-estrategia-de-saude-da-familia-da-cidade-de-alterosa\/","og_site_name":"Federassantas","article_published_time":"2024-02-08T12:52:00+00:00","article_modified_time":"2024-02-08T12:54:55+00:00","og_image":[{"width":828,"height":454,"url":"https:\/\/www.federassantas.org.br\/novosite\/wp-content\/uploads\/2024\/02\/WhatsApp-Image-2024-02-08-at-09.51.24.jpeg","type":"image\/jpeg"}],"author":"admin-federas","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"admin-federas","Est. tempo de leitura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.federassantas.org.br\/novosite\/santa-casa-de-alfenas-realiza-mamografia-em-mulheres-atendidas-pelos-grupos-de-estrategia-de-saude-da-familia-da-cidade-de-alterosa\/#article","isPartOf":{"@id":"https:\/\/www.federassantas.org.br\/novosite\/santa-casa-de-alfenas-realiza-mamografia-em-mulheres-atendidas-pelos-grupos-de-estrategia-de-saude-da-familia-da-cidade-de-alterosa\/"},"author":{"name":"admin-federas","@id":"https:\/\/www.federassantas.org.br\/novosite\/#\/schema\/person\/75fed98158349313fe56175f232f513c"},"headline":"Santa Casa de Alfenas realiza mamografia em mulheres atendidas pelos grupos de Estrat\u00e9gia de Sa\u00fade da Fam\u00edlia da cidade de Alterosa","datePublished":"2024-02-08T12:52:00+00:00","dateModified":"2024-02-08T12:54:55+00:00","mainEntityOfPage":{"@id":"https:\/\/www.federassantas.org.br\/novosite\/santa-casa-de-alfenas-realiza-mamografia-em-mulheres-atendidas-pelos-grupos-de-estrategia-de-saude-da-familia-da-cidade-de-alterosa\/"},"wordCount":258,"commentCount":0,"publisher":{"@id":"https:\/\/www.federassantas.org.br\/novosite\/#organization"},"image":{"@id":"https:\/\/www.federassantas.org.br\/novosite\/santa-casa-de-alfenas-realiza-mamografia-em-mulheres-atendidas-pelos-grupos-de-estrategia-de-saude-da-familia-da-cidade-de-alterosa\/#primaryimage"},"thumbnailUrl":"https:\/\/www.federassantas.org.br\/novosite\/wp-content\/uploads\/2024\/02\/WhatsApp-Image-2024-02-08-at-09.51.24.jpeg","keywords":["Alterosa","mamografia","Santa Casa de Alfenas"],"articleSection":["Not\u00edcias filiados","Regionais","Regional Sul"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.federassantas.org.br\/novosite\/santa-casa-de-alfenas-realiza-mamografia-em-mulheres-atendidas-pelos-grupos-de-estrategia-de-saude-da-familia-da-cidade-de-alterosa\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.federassantas.org.br\/novosite\/santa-casa-de-alfenas-realiza-mamografia-em-mulheres-atendidas-pelos-grupos-de-estrategia-de-saude-da-familia-da-cidade-de-alterosa\/","url":"https:\/\/www.federassantas.org.br\/novosite\/santa-casa-de-alfenas-realiza-mamografia-em-mulheres-atendidas-pelos-grupos-de-estrategia-de-saude-da-familia-da-cidade-de-alterosa\/","name":"Santa Casa de Alfenas realiza mamografia em mulheres atendidas pelos grupos de Estrat\u00e9gia de Sa\u00fade da Fam\u00edlia da cidade de Alterosa - Federassantas","isPartOf":{"@id":"https:\/\/www.federassantas.org.br\/novosite\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.federassantas.org.br\/novosite\/santa-casa-de-alfenas-realiza-mamografia-em-mulheres-atendidas-pelos-grupos-de-estrategia-de-saude-da-familia-da-cidade-de-alterosa\/#primaryimage"},"image":{"@id":"https:\/\/www.federassantas.org.br\/novosite\/santa-casa-de-alfenas-realiza-mamografia-em-mulheres-atendidas-pelos-grupos-de-estrategia-de-saude-da-familia-da-cidade-de-alterosa\/#primaryimage"},"thumbnailUrl":"https:\/\/www.federassantas.org.br\/novosite\/wp-content\/uploads\/2024\/02\/WhatsApp-Image-2024-02-08-at-09.51.24.jpeg","datePublished":"2024-02-08T12:52:00+00:00","dateModified":"2024-02-08T12:54:55+00:00","breadcrumb":{"@id":"https:\/\/www.federassantas.org.br\/novosite\/santa-casa-de-alfenas-realiza-mamografia-em-mulheres-atendidas-pelos-grupos-de-estrategia-de-saude-da-familia-da-cidade-de-alterosa\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.federassantas.org.br\/novosite\/santa-casa-de-alfenas-realiza-mamografia-em-mulheres-atendidas-pelos-grupos-de-estrategia-de-saude-da-familia-da-cidade-de-alterosa\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.federassantas.org.br\/novosite\/santa-casa-de-alfenas-realiza-mamografia-em-mulheres-atendidas-pelos-grupos-de-estrategia-de-saude-da-familia-da-cidade-de-alterosa\/#primaryimage","url":"https:\/\/www.federassantas.org.br\/novosite\/wp-content\/uploads\/2024\/02\/WhatsApp-Image-2024-02-08-at-09.51.24.jpeg","contentUrl":"https:\/\/www.federassantas.org.br\/novosite\/wp-content\/uploads\/2024\/02\/WhatsApp-Image-2024-02-08-at-09.51.24.jpeg","width":828,"height":454},{"@type":"BreadcrumbList","@id":"https:\/\/www.federassantas.org.br\/novosite\/santa-casa-de-alfenas-realiza-mamografia-em-mulheres-atendidas-pelos-grupos-de-estrategia-de-saude-da-familia-da-cidade-de-alterosa\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/www.federassantas.org.br\/novosite\/"},{"@type":"ListItem","position":2,"name":"Santa Casa de Alfenas realiza mamografia em mulheres atendidas pelos grupos de Estrat\u00e9gia de Sa\u00fade da Fam\u00edlia da cidade de Alterosa"}]},{"@type":"WebSite","@id":"https:\/\/www.federassantas.org.br\/novosite\/#website","url":"https:\/\/www.federassantas.org.br\/novosite\/","name":"Federassantas","description":"Entidade de representa\u00e7\u00e3o e fortalecimento das Santas Casas, hospitais filantr\u00f3picos e entidades beneficentes de sa\u00fade de Minas Gerais, atuando na defesa institucional, qualifica\u00e7\u00e3o da gest\u00e3o e sustentabilidade do setor.","publisher":{"@id":"https:\/\/www.federassantas.org.br\/novosite\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.federassantas.org.br\/novosite\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/www.federassantas.org.br\/novosite\/#organization","name":"Federassantas","url":"https:\/\/www.federassantas.org.br\/novosite\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.federassantas.org.br\/novosite\/#\/schema\/logo\/image\/","url":"https:\/\/www.federassantas.org.br\/novosite\/wp-content\/uploads\/2021\/12\/logo.png","contentUrl":"https:\/\/www.federassantas.org.br\/novosite\/wp-content\/uploads\/2021\/12\/logo.png","width":243,"height":59,"caption":"Federassantas"},"image":{"@id":"https:\/\/www.federassantas.org.br\/novosite\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.federassantas.org.br\/novosite\/#\/schema\/person\/75fed98158349313fe56175f232f513c","name":"admin-federas","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.federassantas.org.br\/novosite\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/2a02d7dda59fe8dc6b7ffd3f652e2efede5ccf0dd89dfdc8137c5517f3de8407?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/2a02d7dda59fe8dc6b7ffd3f652e2efede5ccf0dd89dfdc8137c5517f3de8407?s=96&d=mm&r=g","caption":"admin-federas"},"sameAs":["https:\/\/www.federassantas.org.br\/novosite\/"],"url":"https:\/\/www.federassantas.org.br\/novosite\/author\/admin-federas\/"}]}},"_links":{"self":[{"href":"https:\/\/www.federassantas.org.br\/novosite\/wp-json\/wp\/v2\/posts\/31470","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.federassantas.org.br\/novosite\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.federassantas.org.br\/novosite\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.federassantas.org.br\/novosite\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.federassantas.org.br\/novosite\/wp-json\/wp\/v2\/comments?post=31470"}],"version-history":[{"count":4,"href":"https:\/\/www.federassantas.org.br\/novosite\/wp-json\/wp\/v2\/posts\/31470\/revisions"}],"predecessor-version":[{"id":31476,"href":"https:\/\/www.federassantas.org.br\/novosite\/wp-json\/wp\/v2\/posts\/31470\/revisions\/31476"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.federassantas.org.br\/novosite\/wp-json\/wp\/v2\/media\/31471"}],"wp:attachment":[{"href":"https:\/\/www.federassantas.org.br\/novosite\/wp-json\/wp\/v2\/media?parent=31470"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.federassantas.org.br\/novosite\/wp-json\/wp\/v2\/categories?post=31470"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.federassantas.org.br\/novosite\/wp-json\/wp\/v2\/tags?post=31470"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}