{"id":34996,"date":"2024-09-13T18:09:53","date_gmt":"2024-09-13T21:09:53","guid":{"rendered":"https:\/\/www.federassantas.org.br\/novosite\/?p=34996"},"modified":"2024-09-20T18:11:18","modified_gmt":"2024-09-20T21:11:18","slug":"conexao-federassantas-regional-zona-da-mata","status":"publish","type":"post","link":"https:\/\/www.federassantas.org.br\/novosite\/conexao-federassantas-regional-zona-da-mata\/","title":{"rendered":"Conex\u00e3o Federassantas \u2013 Regional Zona da Mata"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"34996\" class=\"elementor elementor-34996\" data-elementor-post-type=\"post\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-50b4e08 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"50b4e08\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-57f82a2\" data-id=\"57f82a2\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-76e8a44 elementor-widget elementor-widget-text-editor\" data-id=\"76e8a44\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Conex\u00e3o Federassantas &#8211; Regional Zona da Mata<\/p><p>\u00c9 com grande entusiasmo que convidamos a toda a Regional Zona da Mata para participar da Conex\u00e3o Federassantas, uma grande oportunidade para debater as demandas das institui\u00e7\u00f5es da regi\u00e3o.<br \/>* Abordagem de forma regional, alinhada \u00e0s estrat\u00e9gias estaduais;<br \/>* Discuss\u00f5es acerca de contratualiza\u00e7\u00e3o, Valora Minas 2.0 e Custos;<br \/>* Troca de experi\u00eancias;<br \/>* Fortalecimento do setor;<br \/>* Constru\u00e7\u00e3o conjunta de solu\u00e7\u00f5es.<\/p><p>Dia 19 de setembro teremos um encontro marcado em Muria\u00e9. \u00c9 imprescind\u00edvel a participa\u00e7\u00e3o do gestor de cada institui\u00e7\u00e3o da regi\u00e3o.<\/p><p>Confirme sua presen\u00e7a no link: https:\/\/tinyurl.com\/2ut39z52<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Conex\u00e3o Federassantas &#8211; Regional Zona da Mata \u00c9 com grande entusiasmo que convidamos a toda a Regional Zona da Mata para participar da Conex\u00e3o Federassantas, uma grande oportunidade para debater as demandas das institui\u00e7\u00f5es da regi\u00e3o. * Abordagem de forma regional, alinhada \u00e0s estrat\u00e9gias estaduais; * Discuss\u00f5es acerca de contratualiza\u00e7\u00e3o, Valora Minas 2.0 e Custos; [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":34997,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[139,249],"tags":[1059,51],"class_list":["post-34996","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias-filiados","category-regional-zona-da-mata","tag-conexao-federassantas","tag-zona-da-mata"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Conex\u00e3o Federassantas \u2013 Regional Zona da Mata - Federassantas<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.federassantas.org.br\/novosite\/conexao-federassantas-regional-zona-da-mata\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Conex\u00e3o Federassantas \u2013 Regional Zona da Mata - Federassantas\" \/>\n<meta property=\"og:description\" content=\"Conex\u00e3o Federassantas &#8211; Regional Zona da Mata \u00c9 com grande entusiasmo que convidamos a toda a Regional Zona da Mata para participar da Conex\u00e3o Federassantas, uma grande oportunidade para debater as demandas das institui\u00e7\u00f5es da regi\u00e3o. * Abordagem de forma regional, alinhada \u00e0s estrat\u00e9gias estaduais; * Discuss\u00f5es acerca de contratualiza\u00e7\u00e3o, Valora Minas 2.0 e Custos; [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.federassantas.org.br\/novosite\/conexao-federassantas-regional-zona-da-mata\/\" \/>\n<meta property=\"og:site_name\" content=\"Federassantas\" \/>\n<meta property=\"article:published_time\" content=\"2024-09-13T21:09:53+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-09-20T21:11:18+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.federassantas.org.br\/novosite\/wp-content\/uploads\/2024\/09\/WhatsApp-Image-2024-09-13-at-11.57.31.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1080\" \/>\n\t<meta property=\"og:image:height\" content=\"1080\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"admin-federas\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin-federas\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.federassantas.org.br\/novosite\/conexao-federassantas-regional-zona-da-mata\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.federassantas.org.br\/novosite\/conexao-federassantas-regional-zona-da-mata\/\"},\"author\":{\"name\":\"admin-federas\",\"@id\":\"https:\/\/www.federassantas.org.br\/novosite\/#\/schema\/person\/75fed98158349313fe56175f232f513c\"},\"headline\":\"Conex\u00e3o Federassantas \u2013 Regional Zona da Mata\",\"datePublished\":\"2024-09-13T21:09:53+00:00\",\"dateModified\":\"2024-09-20T21:11:18+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.federassantas.org.br\/novosite\/conexao-federassantas-regional-zona-da-mata\/\"},\"wordCount\":112,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/www.federassantas.org.br\/novosite\/#organization\"},\"image\":{\"@id\":\"https:\/\/www.federassantas.org.br\/novosite\/conexao-federassantas-regional-zona-da-mata\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.federassantas.org.br\/novosite\/wp-content\/uploads\/2024\/09\/WhatsApp-Image-2024-09-13-at-11.57.31.jpeg\",\"keywords\":[\"Conex\u00e3o Federassantas\",\"Zona da Mata\"],\"articleSection\":[\"Not\u00edcias filiados\",\"Regional Zona Da Mata\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/www.federassantas.org.br\/novosite\/conexao-federassantas-regional-zona-da-mata\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.federassantas.org.br\/novosite\/conexao-federassantas-regional-zona-da-mata\/\",\"url\":\"https:\/\/www.federassantas.org.br\/novosite\/conexao-federassantas-regional-zona-da-mata\/\",\"name\":\"Conex\u00e3o Federassantas \u2013 Regional Zona da Mata - Federassantas\",\"isPartOf\":{\"@id\":\"https:\/\/www.federassantas.org.br\/novosite\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.federassantas.org.br\/novosite\/conexao-federassantas-regional-zona-da-mata\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.federassantas.org.br\/novosite\/conexao-federassantas-regional-zona-da-mata\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.federassantas.org.br\/novosite\/wp-content\/uploads\/2024\/09\/WhatsApp-Image-2024-09-13-at-11.57.31.jpeg\",\"datePublished\":\"2024-09-13T21:09:53+00:00\",\"dateModified\":\"2024-09-20T21:11:18+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.federassantas.org.br\/novosite\/conexao-federassantas-regional-zona-da-mata\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.federassantas.org.br\/novosite\/conexao-federassantas-regional-zona-da-mata\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.federassantas.org.br\/novosite\/conexao-federassantas-regional-zona-da-mata\/#primaryimage\",\"url\":\"https:\/\/www.federassantas.org.br\/novosite\/wp-content\/uploads\/2024\/09\/WhatsApp-Image-2024-09-13-at-11.57.31.jpeg\",\"contentUrl\":\"https:\/\/www.federassantas.org.br\/novosite\/wp-content\/uploads\/2024\/09\/WhatsApp-Image-2024-09-13-at-11.57.31.jpeg\",\"width\":1080,\"height\":1080},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.federassantas.org.br\/novosite\/conexao-federassantas-regional-zona-da-mata\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/www.federassantas.org.br\/novosite\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Conex\u00e3o Federassantas \u2013 Regional Zona da Mata\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.federassantas.org.br\/novosite\/#website\",\"url\":\"https:\/\/www.federassantas.org.br\/novosite\/\",\"name\":\"Federassantas\",\"description\":\"Entidade de representa\u00e7\u00e3o e fortalecimento das Santas Casas, hospitais filantr\u00f3picos e entidades beneficentes de sa\u00fade de Minas Gerais, atuando na defesa institucional, qualifica\u00e7\u00e3o da gest\u00e3o e sustentabilidade do setor.\",\"publisher\":{\"@id\":\"https:\/\/www.federassantas.org.br\/novosite\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.federassantas.org.br\/novosite\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.federassantas.org.br\/novosite\/#organization\",\"name\":\"Federassantas\",\"url\":\"https:\/\/www.federassantas.org.br\/novosite\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.federassantas.org.br\/novosite\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.federassantas.org.br\/novosite\/wp-content\/uploads\/2021\/12\/logo.png\",\"contentUrl\":\"https:\/\/www.federassantas.org.br\/novosite\/wp-content\/uploads\/2021\/12\/logo.png\",\"width\":243,\"height\":59,\"caption\":\"Federassantas\"},\"image\":{\"@id\":\"https:\/\/www.federassantas.org.br\/novosite\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.federassantas.org.br\/novosite\/#\/schema\/person\/75fed98158349313fe56175f232f513c\",\"name\":\"admin-federas\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.federassantas.org.br\/novosite\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/2a02d7dda59fe8dc6b7ffd3f652e2efede5ccf0dd89dfdc8137c5517f3de8407?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/2a02d7dda59fe8dc6b7ffd3f652e2efede5ccf0dd89dfdc8137c5517f3de8407?s=96&d=mm&r=g\",\"caption\":\"admin-federas\"},\"sameAs\":[\"https:\/\/www.federassantas.org.br\/novosite\/\"],\"url\":\"https:\/\/www.federassantas.org.br\/novosite\/author\/admin-federas\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Conex\u00e3o Federassantas \u2013 Regional Zona da Mata - Federassantas","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.federassantas.org.br\/novosite\/conexao-federassantas-regional-zona-da-mata\/","og_locale":"pt_BR","og_type":"article","og_title":"Conex\u00e3o Federassantas \u2013 Regional Zona da Mata - Federassantas","og_description":"Conex\u00e3o Federassantas &#8211; Regional Zona da Mata \u00c9 com grande entusiasmo que convidamos a toda a Regional Zona da Mata para participar da Conex\u00e3o Federassantas, uma grande oportunidade para debater as demandas das institui\u00e7\u00f5es da regi\u00e3o. * Abordagem de forma regional, alinhada \u00e0s estrat\u00e9gias estaduais; * Discuss\u00f5es acerca de contratualiza\u00e7\u00e3o, Valora Minas 2.0 e Custos; [&hellip;]","og_url":"https:\/\/www.federassantas.org.br\/novosite\/conexao-federassantas-regional-zona-da-mata\/","og_site_name":"Federassantas","article_published_time":"2024-09-13T21:09:53+00:00","article_modified_time":"2024-09-20T21:11:18+00:00","og_image":[{"width":1080,"height":1080,"url":"https:\/\/www.federassantas.org.br\/novosite\/wp-content\/uploads\/2024\/09\/WhatsApp-Image-2024-09-13-at-11.57.31.jpeg","type":"image\/jpeg"}],"author":"admin-federas","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"admin-federas","Est. tempo de leitura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.federassantas.org.br\/novosite\/conexao-federassantas-regional-zona-da-mata\/#article","isPartOf":{"@id":"https:\/\/www.federassantas.org.br\/novosite\/conexao-federassantas-regional-zona-da-mata\/"},"author":{"name":"admin-federas","@id":"https:\/\/www.federassantas.org.br\/novosite\/#\/schema\/person\/75fed98158349313fe56175f232f513c"},"headline":"Conex\u00e3o Federassantas \u2013 Regional Zona da Mata","datePublished":"2024-09-13T21:09:53+00:00","dateModified":"2024-09-20T21:11:18+00:00","mainEntityOfPage":{"@id":"https:\/\/www.federassantas.org.br\/novosite\/conexao-federassantas-regional-zona-da-mata\/"},"wordCount":112,"commentCount":0,"publisher":{"@id":"https:\/\/www.federassantas.org.br\/novosite\/#organization"},"image":{"@id":"https:\/\/www.federassantas.org.br\/novosite\/conexao-federassantas-regional-zona-da-mata\/#primaryimage"},"thumbnailUrl":"https:\/\/www.federassantas.org.br\/novosite\/wp-content\/uploads\/2024\/09\/WhatsApp-Image-2024-09-13-at-11.57.31.jpeg","keywords":["Conex\u00e3o Federassantas","Zona da Mata"],"articleSection":["Not\u00edcias filiados","Regional Zona Da Mata"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.federassantas.org.br\/novosite\/conexao-federassantas-regional-zona-da-mata\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.federassantas.org.br\/novosite\/conexao-federassantas-regional-zona-da-mata\/","url":"https:\/\/www.federassantas.org.br\/novosite\/conexao-federassantas-regional-zona-da-mata\/","name":"Conex\u00e3o Federassantas \u2013 Regional Zona da Mata - Federassantas","isPartOf":{"@id":"https:\/\/www.federassantas.org.br\/novosite\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.federassantas.org.br\/novosite\/conexao-federassantas-regional-zona-da-mata\/#primaryimage"},"image":{"@id":"https:\/\/www.federassantas.org.br\/novosite\/conexao-federassantas-regional-zona-da-mata\/#primaryimage"},"thumbnailUrl":"https:\/\/www.federassantas.org.br\/novosite\/wp-content\/uploads\/2024\/09\/WhatsApp-Image-2024-09-13-at-11.57.31.jpeg","datePublished":"2024-09-13T21:09:53+00:00","dateModified":"2024-09-20T21:11:18+00:00","breadcrumb":{"@id":"https:\/\/www.federassantas.org.br\/novosite\/conexao-federassantas-regional-zona-da-mata\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.federassantas.org.br\/novosite\/conexao-federassantas-regional-zona-da-mata\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.federassantas.org.br\/novosite\/conexao-federassantas-regional-zona-da-mata\/#primaryimage","url":"https:\/\/www.federassantas.org.br\/novosite\/wp-content\/uploads\/2024\/09\/WhatsApp-Image-2024-09-13-at-11.57.31.jpeg","contentUrl":"https:\/\/www.federassantas.org.br\/novosite\/wp-content\/uploads\/2024\/09\/WhatsApp-Image-2024-09-13-at-11.57.31.jpeg","width":1080,"height":1080},{"@type":"BreadcrumbList","@id":"https:\/\/www.federassantas.org.br\/novosite\/conexao-federassantas-regional-zona-da-mata\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/www.federassantas.org.br\/novosite\/"},{"@type":"ListItem","position":2,"name":"Conex\u00e3o Federassantas \u2013 Regional Zona da Mata"}]},{"@type":"WebSite","@id":"https:\/\/www.federassantas.org.br\/novosite\/#website","url":"https:\/\/www.federassantas.org.br\/novosite\/","name":"Federassantas","description":"Entidade de representa\u00e7\u00e3o e fortalecimento das Santas Casas, hospitais filantr\u00f3picos e entidades beneficentes de sa\u00fade de Minas Gerais, atuando na defesa institucional, qualifica\u00e7\u00e3o da gest\u00e3o e sustentabilidade do setor.","publisher":{"@id":"https:\/\/www.federassantas.org.br\/novosite\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.federassantas.org.br\/novosite\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/www.federassantas.org.br\/novosite\/#organization","name":"Federassantas","url":"https:\/\/www.federassantas.org.br\/novosite\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.federassantas.org.br\/novosite\/#\/schema\/logo\/image\/","url":"https:\/\/www.federassantas.org.br\/novosite\/wp-content\/uploads\/2021\/12\/logo.png","contentUrl":"https:\/\/www.federassantas.org.br\/novosite\/wp-content\/uploads\/2021\/12\/logo.png","width":243,"height":59,"caption":"Federassantas"},"image":{"@id":"https:\/\/www.federassantas.org.br\/novosite\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.federassantas.org.br\/novosite\/#\/schema\/person\/75fed98158349313fe56175f232f513c","name":"admin-federas","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.federassantas.org.br\/novosite\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/2a02d7dda59fe8dc6b7ffd3f652e2efede5ccf0dd89dfdc8137c5517f3de8407?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/2a02d7dda59fe8dc6b7ffd3f652e2efede5ccf0dd89dfdc8137c5517f3de8407?s=96&d=mm&r=g","caption":"admin-federas"},"sameAs":["https:\/\/www.federassantas.org.br\/novosite\/"],"url":"https:\/\/www.federassantas.org.br\/novosite\/author\/admin-federas\/"}]}},"_links":{"self":[{"href":"https:\/\/www.federassantas.org.br\/novosite\/wp-json\/wp\/v2\/posts\/34996","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.federassantas.org.br\/novosite\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.federassantas.org.br\/novosite\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.federassantas.org.br\/novosite\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.federassantas.org.br\/novosite\/wp-json\/wp\/v2\/comments?post=34996"}],"version-history":[{"count":5,"href":"https:\/\/www.federassantas.org.br\/novosite\/wp-json\/wp\/v2\/posts\/34996\/revisions"}],"predecessor-version":[{"id":35002,"href":"https:\/\/www.federassantas.org.br\/novosite\/wp-json\/wp\/v2\/posts\/34996\/revisions\/35002"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.federassantas.org.br\/novosite\/wp-json\/wp\/v2\/media\/34997"}],"wp:attachment":[{"href":"https:\/\/www.federassantas.org.br\/novosite\/wp-json\/wp\/v2\/media?parent=34996"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.federassantas.org.br\/novosite\/wp-json\/wp\/v2\/categories?post=34996"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.federassantas.org.br\/novosite\/wp-json\/wp\/v2\/tags?post=34996"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}