{"id":38495,"date":"2025-08-20T16:52:09","date_gmt":"2025-08-20T19:52:09","guid":{"rendered":"https:\/\/www.federassantas.org.br\/novosite\/?p=38495"},"modified":"2025-08-20T16:52:09","modified_gmt":"2025-08-20T19:52:09","slug":"santa-casa-bh-recebe-edicao-do-do-dialogo-saude-regional-oncologia","status":"publish","type":"post","link":"https:\/\/www.federassantas.org.br\/novosite\/santa-casa-bh-recebe-edicao-do-do-dialogo-saude-regional-oncologia\/","title":{"rendered":"Santa Casa BH recebe edi\u00e7\u00e3o do do \u2018Di\u00e1logo Sa\u00fade Regional Oncologia\u2019"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"38495\" class=\"elementor elementor-38495\" data-elementor-post-type=\"post\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-a633226 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"a633226\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-e1d79f9\" data-id=\"e1d79f9\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ad186dd elementor-widget elementor-widget-text-editor\" data-id=\"ad186dd\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div>Nos dias 21 e 22 de agosto, o Instituto Lado a Lado pela Vida promover\u00e1, em parceria com a Santa Casa BH, a segunda edi\u00e7\u00e3o do \u2018Di\u00e1logo Sa\u00fade Regional Oncologia\u2019 &#8211; iniciativa que ir\u00e1 percorrer o pa\u00eds para promover discuss\u00f5es sobre os desafios regionais no enfrentamento do c\u00e2ncer. O <strong>evento acontece das 8h \u00e0s 18h, na quinta-feira (21\/08),<\/strong> e reunir\u00e1 gestores p\u00fablicos, especialistas, parlamentares e representantes da sociedade civil para entender a realidade do c\u00e2ncer no estado mineiro. J\u00e1 o segundo dia (22\/08), ser\u00e1 dedicado exclusivamente aos pacientes oncol\u00f3gicos, com programa\u00e7\u00e3o das 8h \u00e0s 18h, em que ocorrer\u00e3o palestras com tem\u00e1ticas voltadas \u00e0 jornada do paciente no enfrentamento do c\u00e2ncer. \u00a0 \u00a0<\/div><div>\u00a0<\/div><div>O objetivo do \u2018Di\u00e1logo Sa\u00fade Regional Oncologia\u2019 \u00e9 promover o debate e levantamento das demandas locais, dar visibilidade aos desafios enfrentados pelos gestores dos centros e hospitais de m\u00e9dia e alta complexidade e, a partir de dados regionais, construir caminhos vi\u00e1veis para a efetiva implementa\u00e7\u00e3o da PNPCC, institu\u00edda pela Lei n\u00ba 14.758\/2023.\u00a0<strong>\u201cPara a edi\u00e7\u00e3o mineira, estar pr\u00f3ximo aos atores locais e ter a Santa Casa BH como parceira, como na edi\u00e7\u00e3o em 2024, faz toda diferen\u00e7a, pois amplia o debate ao trazer as realidades regionais e maior visibilidade para as necessidades enfrentadas pelos pacientes oncol\u00f3gicos\u201d<\/strong>, salienta.<\/div><div>\u00a0<\/div><div>Marlene Oliveira, fundadora e presidente do Instituto Lado a Lado pela Vida. No encontro, ser\u00e3o realizados cinco pain\u00e9is para discutir o cen\u00e1rio do c\u00e2ncer em Minas Gerais: o financiamento na oncologia; o enfrentamento dos vazios assistenciais no Estado; a rede oncol\u00f3gica mineira desde regula\u00e7\u00e3o at\u00e9 a descentraliza\u00e7\u00e3o do cuidado e a navega\u00e7\u00e3o do paciente oncol\u00f3gico no SUS.<\/div><div>O \u2018Di\u00e1logo Sa\u00fade Regional Oncologia\u2019 \u00e9 uma a\u00e7\u00e3o que integra o Programa Caminhos da Sa\u00fade, que visa a promo\u00e7\u00e3o de a\u00e7\u00f5es integradas \u00e0 sa\u00fade, educa\u00e7\u00e3o e cultura, que contribuam para a preven\u00e7\u00e3o de doen\u00e7as e o diagn\u00f3stico precoce do c\u00e2ncer. Segundo Marlene Oliveira, o encontro ser\u00e1 importante para contribuir com a jornada dos pacientes oncol\u00f3gicos, seus principais desafios, bem como debater proposi\u00e7\u00f5es visando a implementa\u00e7\u00e3o da nova pol\u00edtica nacional do c\u00e2ncer, para ser uma lei funcional e efetiva para os pacientes. <strong>\u201cA PNPCC \u00e9 uma conquista coletiva da sociedade brasileira e precisa ser materializada na ponta, respeitando as especificidades de cada territ\u00f3rio. \u00c9 por isso que seguimos mobilizando diferentes regi\u00f5es do Pa\u00eds, promovendo o di\u00e1logo como ferramenta de transforma\u00e7\u00e3o\u201d<\/strong>, afirma Marlene.<\/div><div>\u00a0<\/div><div>Para a gerente do instituto de oncologia da Santa Casa BH, Sara Oliveira, esse \u00e9 um momento importante para fortalecer o debate ao integrar a viv\u00eancia local com a capacidade de mobiliza\u00e7\u00e3o nacional. <strong>\u201cN\u00f3s temos desafios para lidar como os vazios assistenciais, regula\u00e7\u00e3o lenta, concentra\u00e7\u00e3o de servi\u00e7os e falta de financiamento sustent\u00e1vel. Ao recebermos este encontro, reunimos atores-chave para propor solu\u00e7\u00f5es vi\u00e1veis, contribuindo para formaliz\u00e1-las em uma nota t\u00e9cnica aos \u00f3rg\u00e3os de sa\u00fade em uma iniciativa do Instituto Lado a Lado pela Vida visando propositividade. Isso garante que a PNPCC seja discutida com base em dados reais e adaptada \u00e0s necessidades regionais\u201d<\/strong>, complementa Sara.\u2002\u2002\u2002\u2002\u2002<\/div><div>\u00a0<\/div><div>Mais do que um evento, o \u2018Di\u00e1logo Sa\u00fade Regional Oncologia\u2019 se consolida como um movimento de articula\u00e7\u00e3o e a\u00e7\u00e3o em defesa do cuidado oncol\u00f3gico justo, integral e humanizado em todas as etapas da jornada do paciente. Esta iniciativa refor\u00e7a o compromisso do Instituto Lado a Lado pela Vida com a transforma\u00e7\u00e3o da sa\u00fade p\u00fablica brasileira e com a constru\u00e7\u00e3o de pol\u00edticas p\u00fablicas que coloquem o paciente no centro do cuidado. <strong>\u201cSabemos que o c\u00e2ncer n\u00e3o espera e a mudan\u00e7a acontece quando transformamos inten\u00e7\u00e3o em a\u00e7\u00e3o. Ap\u00f3s os encontros regionais, produziremos uma nota t\u00e9cnica que ser\u00e1 enviada ao Minist\u00e9rio da Sa\u00fade e Secretarias de Sa\u00fade para apontamentos e poss\u00edveis a\u00e7\u00f5es para que a lei seja cumprida e transforme a vida das pessoas\u201d<\/strong>, explica Marlene. \u00a0<\/div><div>\u00a0<\/div><div>Criado em 2024, o projeto nasceu com duas edi\u00e7\u00f5es em Minas Gerais e Bras\u00edlia, al\u00e9m de uma edi\u00e7\u00e3o especial dentro do Global F\u00f3rum Fronteiras da Sa\u00fade. Em 2025, o \u2018Di\u00e1logo Sa\u00fade Regional Oncologia\u2019 ganha for\u00e7a e se expande para outros estados e munic\u00edpios que enfrentam dificuldades na \u00e1rea oncol\u00f3gica, como a regula\u00e7\u00e3o de servi\u00e7os, o deslocamento de pacientes em busca de tratamento e os desafios de financiamento e sustentabilidade das pol\u00edticas de sa\u00fade.\u00a0Para Marlene, o encontro \u00e9 um convite para que todos os envolvidos na luta contra o c\u00e2ncer se engajem e contribuam para que o acesso igualit\u00e1rio aos tratamentos e a qualidade de vida dos pacientes sejam prioridades no Pa\u00eds. <strong>\u201cAl\u00e9m de tra\u00e7ar um panorama do que est\u00e1 acontecendo com rela\u00e7\u00e3o ao c\u00e2ncer, vamos debater os gargalos e desafios que o paciente enfrenta\u201d<\/strong>, conclui.<\/div><div>\u00a0<\/div><div>As inscri\u00e7\u00f5es s\u00e3o gratuitas e podem ser realizadas por meio do site:<\/div><div><a id=\"m_1435525776713001082LPlnk903021\" title=\"https:\/\/lp.ladoaladopelavida.org.br\/2025-evento-dialogo-saude-regional-minas-gerais\" href=\"https:\/\/lp.ladoaladopelavida.org.br\/2025-evento-dialogo-saude-regional-minas-gerais\" target=\"_blank\" rel=\"noopener\" data-saferedirecturl=\"https:\/\/www.google.com\/url?q=https:\/\/lp.ladoaladopelavida.org.br\/2025-evento-dialogo-saude-regional-minas-gerais&amp;source=gmail&amp;ust=1755799229606000&amp;usg=AOvVaw3YWws3oali6BmsB0bjpCdU\">https:\/\/lp.ladoaladopelavida.<wbr \/>org.br\/2025-evento-dialogo-<wbr \/>saude-regional-minas-gerais<\/a><\/div><div>\u00a0<\/div><div><b>SERVI\u00c7O<\/b><\/div><div>Di\u00e1logo Sa\u00fade Regional Oncologia Minas Gerais<\/div><div>Data: 21 e 22 de agosto (quinta-feira e sexta-feira) das 8h \u00e0s 18h<\/div><div>Local: Santa Casa de Belo Horizonte<\/div><div>Endere\u00e7o: Rua Cear\u00e1 333, Santa Efig\u00eania, Belo Horizonte.<\/div><div>\u00a0<\/div><div>Sobre o Instituto Lado a Lado pela Vida<\/div><div>\u00a0<\/div><div>Fundado em 2008, o Instituto Lado a Lado pela Vida \u00e9 uma Organiza\u00e7\u00e3o da Sociedade Civil que atua na preven\u00e7\u00e3o, diagn\u00f3stico precoce e no cuidado integral de doen\u00e7as cr\u00f4nicas como o c\u00e2ncer e as doen\u00e7as cardiovasculares, al\u00e9m do intenso trabalho relacionado \u00e0 sa\u00fade do homem. Todas as iniciativas do Instituto s\u00e3o guiadas pelo Programa Caminhos da Sa\u00fade, que visa a promo\u00e7\u00e3o de a\u00e7\u00f5es integradas \u00e0 sa\u00fade, educa\u00e7\u00e3o e cultura, que contribuam para a preven\u00e7\u00e3o de doen\u00e7as e o diagn\u00f3stico precoce das duas principais causas de mortalidade no pa\u00eds \u2014 o c\u00e2ncer e as doen\u00e7as cardiovasculares. Esse caminho \u00e9 constru\u00eddo com a viv\u00eancia da institui\u00e7\u00e3o junto \u00e0s realidades locais, fortalecendo o v\u00ednculo com comunidades e gestores e a partir da coleta e an\u00e1lise de dados regionais. O programa orienta estrat\u00e9gias em sa\u00fade p\u00fablica e fortalece o papel do Instituto como agente de advocacy, com forte presen\u00e7a na articula\u00e7\u00e3o de pol\u00edticas p\u00fablicas e a\u00e7\u00f5es de impacto social. Idealizador do Novembro Azul \u2014 o maior movimento em prol da sa\u00fade do homem no Brasil \u2014 e de campanhas como Respire Agosto, Siga seu Cora\u00e7\u00e3o e Mulher Por Inteiro e C\u00e2ncer por HPV: o Brasil pode ficar sem, o Instituto alia informa\u00e7\u00e3o de qualidade, mobiliza\u00e7\u00e3o, engajamento comunit\u00e1rio e escuta ativa em sua atua\u00e7\u00e3o nos territ\u00f3rios. A organiza\u00e7\u00e3o \u00e9 a \u00fanica representante na Am\u00e9rica Latina no Comit\u00ea de Advocacy da World Heart Federation.<\/div><div>\u00a0<\/div><div>Site:\u00a0<a id=\"m_1435525776713001082LPlnk571651\" title=\"https:\/\/ladoaladopelavida.org.br\/\" href=\"https:\/\/ladoaladopelavida.org.br\/\" target=\"_blank\" rel=\"noopener\" data-saferedirecturl=\"https:\/\/www.google.com\/url?q=https:\/\/ladoaladopelavida.org.br\/&amp;source=gmail&amp;ust=1755799229606000&amp;usg=AOvVaw108FEI7Q620cm-1uX03J6a\">https:\/\/ladoaladopelavida.org.<wbr \/>br\/<\/a><\/div><div><b>\u00a0<\/b><\/div><div><b>Sobre o Instituto de Oncologia da Santa Casa BH<\/b><\/div><div><b>\u00a0<\/b><\/div><div>Pioneira no atendimento a pacientes oncol\u00f3gicos em Minas Gerais, a Santa Casa BH acumula mais de 100 anos de experi\u00eancia no tratamento da doen\u00e7a. O Instituto de Oncologia oferece toda a linha de cuidado pelo Sistema \u00danico de Sa\u00fade (SUS), abrangendo consultas cl\u00ednicas, atendimento ambulatorial, quimioterapia, radioterapia, interna\u00e7\u00f5es e cirurgias oncol\u00f3gicas, entre outros servi\u00e7os.<\/div><div>\u00a0<\/div><div>A Santa Casa BH investe continuamente em inova\u00e7\u00e3o, sendo um dos poucos hospitais do estado a contar com dois aceleradores lineares, equipamentos de \u00faltima gera\u00e7\u00e3o utilizados no tratamento por radioterapia. Essa estrutura avan\u00e7ada permite dobrar a capacidade de atendimento e reduzir significativamente a fila de espera, garantindo acesso mais r\u00e1pido e eficiente \u00e0 terapia oncol\u00f3gica.<\/div><div>\u00a0<\/div><div>Em 2024, a unidade registrou 82.293 atendimentos adultos e pedi\u00e1tricos, consolidando-se como o \u00fanico servi\u00e7o do estado com uma estrutura integrada para todas as necessidades do tratamento oncol\u00f3gico em um \u00fanico local. O instituto conta com 13 especialidades, entre elas oncologia cl\u00ednica e pedi\u00e1trica, onco-hematologia, radioncologia, mastologia, urologia, coloproctologia, cirurgia oncol\u00f3gica geral e tor\u00e1cica.<\/div><div>\u00a0<\/div><div>Para dimensionar a grandiosidade do instituto, apenas em 2024 foram realizados:<\/div><ul><li><div role=\"presentation\">22.225 tratamentos oncol\u00f3gicos, incluindo sess\u00f5es de quimioterapia (pedi\u00e1trica e adulta) e hormonioterapia;<\/div><\/li><li><div role=\"presentation\">23.680 consultas em especialidades cir\u00fargicas;<\/div><\/li><li><div role=\"presentation\">20.685 sess\u00f5es de radioterapia.<\/div><div><div role=\"presentation\">\u00a0<\/div><\/div><\/li><\/ul><div>Site:\u00a0<a id=\"m_1435525776713001082LPlnk137025\" title=\"https:\/\/santacasabh.org.br\/\" href=\"https:\/\/santacasabh.org.br\/\" target=\"_blank\" rel=\"noopener\" data-saferedirecturl=\"https:\/\/www.google.com\/url?q=https:\/\/santacasabh.org.br\/&amp;source=gmail&amp;ust=1755799229607000&amp;usg=AOvVaw0ecwVWzdinAWarUgadljxU\">https:\/\/santacasabh.org.br\/<\/a><\/div><div>\u00a0<\/div><div>Fonte: Assessoria de Comunica\u00e7\u00e3o Santa Casa BH<\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Nos dias 21 e 22 de agosto, o Instituto Lado a Lado pela Vida promover\u00e1, em parceria com a Santa Casa BH, a segunda edi\u00e7\u00e3o do \u2018Di\u00e1logo Sa\u00fade Regional Oncologia\u2019 &#8211; iniciativa que ir\u00e1 percorrer o pa\u00eds para promover discuss\u00f5es sobre os desafios regionais no enfrentamento do c\u00e2ncer. O evento acontece das 8h \u00e0s 18h, [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":38501,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[140],"tags":[],"class_list":["post-38495","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Santa Casa BH recebe edi\u00e7\u00e3o do do \u2018Di\u00e1logo Sa\u00fade Regional Oncologia\u2019 - Federassantas<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.federassantas.org.br\/novosite\/santa-casa-bh-recebe-edicao-do-do-dialogo-saude-regional-oncologia\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Santa Casa BH recebe edi\u00e7\u00e3o do do \u2018Di\u00e1logo Sa\u00fade Regional Oncologia\u2019 - Federassantas\" \/>\n<meta property=\"og:description\" content=\"Nos dias 21 e 22 de agosto, o Instituto Lado a Lado pela Vida promover\u00e1, em parceria com a Santa Casa BH, a segunda edi\u00e7\u00e3o do \u2018Di\u00e1logo Sa\u00fade Regional Oncologia\u2019 &#8211; iniciativa que ir\u00e1 percorrer o pa\u00eds para promover discuss\u00f5es sobre os desafios regionais no enfrentamento do c\u00e2ncer. O evento acontece das 8h \u00e0s 18h, [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.federassantas.org.br\/novosite\/santa-casa-bh-recebe-edicao-do-do-dialogo-saude-regional-oncologia\/\" \/>\n<meta property=\"og:site_name\" content=\"Federassantas\" \/>\n<meta property=\"article:published_time\" content=\"2025-08-20T19:52:09+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.federassantas.org.br\/novosite\/wp-content\/uploads\/2025\/08\/TAMANHO-PARA-BANNER-SITE-33.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1120\" \/>\n\t<meta property=\"og:image:height\" content=\"730\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"admin-federas\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin-federas\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"7 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.federassantas.org.br\/novosite\/santa-casa-bh-recebe-edicao-do-do-dialogo-saude-regional-oncologia\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.federassantas.org.br\/novosite\/santa-casa-bh-recebe-edicao-do-do-dialogo-saude-regional-oncologia\/\"},\"author\":{\"name\":\"admin-federas\",\"@id\":\"https:\/\/www.federassantas.org.br\/novosite\/#\/schema\/person\/75fed98158349313fe56175f232f513c\"},\"headline\":\"Santa Casa BH recebe edi\u00e7\u00e3o do do \u2018Di\u00e1logo Sa\u00fade Regional Oncologia\u2019\",\"datePublished\":\"2025-08-20T19:52:09+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.federassantas.org.br\/novosite\/santa-casa-bh-recebe-edicao-do-do-dialogo-saude-regional-oncologia\/\"},\"wordCount\":1421,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/www.federassantas.org.br\/novosite\/#organization\"},\"image\":{\"@id\":\"https:\/\/www.federassantas.org.br\/novosite\/santa-casa-bh-recebe-edicao-do-do-dialogo-saude-regional-oncologia\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.federassantas.org.br\/novosite\/wp-content\/uploads\/2025\/08\/TAMANHO-PARA-BANNER-SITE-33.png\",\"articleSection\":[\"Not\u00edcias\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/www.federassantas.org.br\/novosite\/santa-casa-bh-recebe-edicao-do-do-dialogo-saude-regional-oncologia\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.federassantas.org.br\/novosite\/santa-casa-bh-recebe-edicao-do-do-dialogo-saude-regional-oncologia\/\",\"url\":\"https:\/\/www.federassantas.org.br\/novosite\/santa-casa-bh-recebe-edicao-do-do-dialogo-saude-regional-oncologia\/\",\"name\":\"Santa Casa BH recebe edi\u00e7\u00e3o do do \u2018Di\u00e1logo Sa\u00fade Regional Oncologia\u2019 - Federassantas\",\"isPartOf\":{\"@id\":\"https:\/\/www.federassantas.org.br\/novosite\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.federassantas.org.br\/novosite\/santa-casa-bh-recebe-edicao-do-do-dialogo-saude-regional-oncologia\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.federassantas.org.br\/novosite\/santa-casa-bh-recebe-edicao-do-do-dialogo-saude-regional-oncologia\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.federassantas.org.br\/novosite\/wp-content\/uploads\/2025\/08\/TAMANHO-PARA-BANNER-SITE-33.png\",\"datePublished\":\"2025-08-20T19:52:09+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.federassantas.org.br\/novosite\/santa-casa-bh-recebe-edicao-do-do-dialogo-saude-regional-oncologia\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.federassantas.org.br\/novosite\/santa-casa-bh-recebe-edicao-do-do-dialogo-saude-regional-oncologia\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.federassantas.org.br\/novosite\/santa-casa-bh-recebe-edicao-do-do-dialogo-saude-regional-oncologia\/#primaryimage\",\"url\":\"https:\/\/www.federassantas.org.br\/novosite\/wp-content\/uploads\/2025\/08\/TAMANHO-PARA-BANNER-SITE-33.png\",\"contentUrl\":\"https:\/\/www.federassantas.org.br\/novosite\/wp-content\/uploads\/2025\/08\/TAMANHO-PARA-BANNER-SITE-33.png\",\"width\":1120,\"height\":730},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.federassantas.org.br\/novosite\/santa-casa-bh-recebe-edicao-do-do-dialogo-saude-regional-oncologia\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/www.federassantas.org.br\/novosite\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Santa Casa BH recebe edi\u00e7\u00e3o do do \u2018Di\u00e1logo Sa\u00fade Regional Oncologia\u2019\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.federassantas.org.br\/novosite\/#website\",\"url\":\"https:\/\/www.federassantas.org.br\/novosite\/\",\"name\":\"Federassantas\",\"description\":\"Entidade de representa\u00e7\u00e3o e fortalecimento das Santas Casas, hospitais filantr\u00f3picos e entidades beneficentes de sa\u00fade de Minas Gerais, atuando na defesa institucional, qualifica\u00e7\u00e3o da gest\u00e3o e sustentabilidade do setor.\",\"publisher\":{\"@id\":\"https:\/\/www.federassantas.org.br\/novosite\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.federassantas.org.br\/novosite\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.federassantas.org.br\/novosite\/#organization\",\"name\":\"Federassantas\",\"url\":\"https:\/\/www.federassantas.org.br\/novosite\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.federassantas.org.br\/novosite\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.federassantas.org.br\/novosite\/wp-content\/uploads\/2021\/12\/logo.png\",\"contentUrl\":\"https:\/\/www.federassantas.org.br\/novosite\/wp-content\/uploads\/2021\/12\/logo.png\",\"width\":243,\"height\":59,\"caption\":\"Federassantas\"},\"image\":{\"@id\":\"https:\/\/www.federassantas.org.br\/novosite\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.federassantas.org.br\/novosite\/#\/schema\/person\/75fed98158349313fe56175f232f513c\",\"name\":\"admin-federas\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.federassantas.org.br\/novosite\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/2a02d7dda59fe8dc6b7ffd3f652e2efede5ccf0dd89dfdc8137c5517f3de8407?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/2a02d7dda59fe8dc6b7ffd3f652e2efede5ccf0dd89dfdc8137c5517f3de8407?s=96&d=mm&r=g\",\"caption\":\"admin-federas\"},\"sameAs\":[\"https:\/\/www.federassantas.org.br\/novosite\/\"],\"url\":\"https:\/\/www.federassantas.org.br\/novosite\/author\/admin-federas\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Santa Casa BH recebe edi\u00e7\u00e3o do do \u2018Di\u00e1logo Sa\u00fade Regional Oncologia\u2019 - Federassantas","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.federassantas.org.br\/novosite\/santa-casa-bh-recebe-edicao-do-do-dialogo-saude-regional-oncologia\/","og_locale":"pt_BR","og_type":"article","og_title":"Santa Casa BH recebe edi\u00e7\u00e3o do do \u2018Di\u00e1logo Sa\u00fade Regional Oncologia\u2019 - Federassantas","og_description":"Nos dias 21 e 22 de agosto, o Instituto Lado a Lado pela Vida promover\u00e1, em parceria com a Santa Casa BH, a segunda edi\u00e7\u00e3o do \u2018Di\u00e1logo Sa\u00fade Regional Oncologia\u2019 &#8211; iniciativa que ir\u00e1 percorrer o pa\u00eds para promover discuss\u00f5es sobre os desafios regionais no enfrentamento do c\u00e2ncer. O evento acontece das 8h \u00e0s 18h, [&hellip;]","og_url":"https:\/\/www.federassantas.org.br\/novosite\/santa-casa-bh-recebe-edicao-do-do-dialogo-saude-regional-oncologia\/","og_site_name":"Federassantas","article_published_time":"2025-08-20T19:52:09+00:00","og_image":[{"width":1120,"height":730,"url":"https:\/\/www.federassantas.org.br\/novosite\/wp-content\/uploads\/2025\/08\/TAMANHO-PARA-BANNER-SITE-33.png","type":"image\/png"}],"author":"admin-federas","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"admin-federas","Est. tempo de leitura":"7 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.federassantas.org.br\/novosite\/santa-casa-bh-recebe-edicao-do-do-dialogo-saude-regional-oncologia\/#article","isPartOf":{"@id":"https:\/\/www.federassantas.org.br\/novosite\/santa-casa-bh-recebe-edicao-do-do-dialogo-saude-regional-oncologia\/"},"author":{"name":"admin-federas","@id":"https:\/\/www.federassantas.org.br\/novosite\/#\/schema\/person\/75fed98158349313fe56175f232f513c"},"headline":"Santa Casa BH recebe edi\u00e7\u00e3o do do \u2018Di\u00e1logo Sa\u00fade Regional Oncologia\u2019","datePublished":"2025-08-20T19:52:09+00:00","mainEntityOfPage":{"@id":"https:\/\/www.federassantas.org.br\/novosite\/santa-casa-bh-recebe-edicao-do-do-dialogo-saude-regional-oncologia\/"},"wordCount":1421,"commentCount":0,"publisher":{"@id":"https:\/\/www.federassantas.org.br\/novosite\/#organization"},"image":{"@id":"https:\/\/www.federassantas.org.br\/novosite\/santa-casa-bh-recebe-edicao-do-do-dialogo-saude-regional-oncologia\/#primaryimage"},"thumbnailUrl":"https:\/\/www.federassantas.org.br\/novosite\/wp-content\/uploads\/2025\/08\/TAMANHO-PARA-BANNER-SITE-33.png","articleSection":["Not\u00edcias"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.federassantas.org.br\/novosite\/santa-casa-bh-recebe-edicao-do-do-dialogo-saude-regional-oncologia\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.federassantas.org.br\/novosite\/santa-casa-bh-recebe-edicao-do-do-dialogo-saude-regional-oncologia\/","url":"https:\/\/www.federassantas.org.br\/novosite\/santa-casa-bh-recebe-edicao-do-do-dialogo-saude-regional-oncologia\/","name":"Santa Casa BH recebe edi\u00e7\u00e3o do do \u2018Di\u00e1logo Sa\u00fade Regional Oncologia\u2019 - Federassantas","isPartOf":{"@id":"https:\/\/www.federassantas.org.br\/novosite\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.federassantas.org.br\/novosite\/santa-casa-bh-recebe-edicao-do-do-dialogo-saude-regional-oncologia\/#primaryimage"},"image":{"@id":"https:\/\/www.federassantas.org.br\/novosite\/santa-casa-bh-recebe-edicao-do-do-dialogo-saude-regional-oncologia\/#primaryimage"},"thumbnailUrl":"https:\/\/www.federassantas.org.br\/novosite\/wp-content\/uploads\/2025\/08\/TAMANHO-PARA-BANNER-SITE-33.png","datePublished":"2025-08-20T19:52:09+00:00","breadcrumb":{"@id":"https:\/\/www.federassantas.org.br\/novosite\/santa-casa-bh-recebe-edicao-do-do-dialogo-saude-regional-oncologia\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.federassantas.org.br\/novosite\/santa-casa-bh-recebe-edicao-do-do-dialogo-saude-regional-oncologia\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.federassantas.org.br\/novosite\/santa-casa-bh-recebe-edicao-do-do-dialogo-saude-regional-oncologia\/#primaryimage","url":"https:\/\/www.federassantas.org.br\/novosite\/wp-content\/uploads\/2025\/08\/TAMANHO-PARA-BANNER-SITE-33.png","contentUrl":"https:\/\/www.federassantas.org.br\/novosite\/wp-content\/uploads\/2025\/08\/TAMANHO-PARA-BANNER-SITE-33.png","width":1120,"height":730},{"@type":"BreadcrumbList","@id":"https:\/\/www.federassantas.org.br\/novosite\/santa-casa-bh-recebe-edicao-do-do-dialogo-saude-regional-oncologia\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/www.federassantas.org.br\/novosite\/"},{"@type":"ListItem","position":2,"name":"Santa Casa BH recebe edi\u00e7\u00e3o do do \u2018Di\u00e1logo Sa\u00fade Regional Oncologia\u2019"}]},{"@type":"WebSite","@id":"https:\/\/www.federassantas.org.br\/novosite\/#website","url":"https:\/\/www.federassantas.org.br\/novosite\/","name":"Federassantas","description":"Entidade de representa\u00e7\u00e3o e fortalecimento das Santas Casas, hospitais filantr\u00f3picos e entidades beneficentes de sa\u00fade de Minas Gerais, atuando na defesa institucional, qualifica\u00e7\u00e3o da gest\u00e3o e sustentabilidade do setor.","publisher":{"@id":"https:\/\/www.federassantas.org.br\/novosite\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.federassantas.org.br\/novosite\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/www.federassantas.org.br\/novosite\/#organization","name":"Federassantas","url":"https:\/\/www.federassantas.org.br\/novosite\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.federassantas.org.br\/novosite\/#\/schema\/logo\/image\/","url":"https:\/\/www.federassantas.org.br\/novosite\/wp-content\/uploads\/2021\/12\/logo.png","contentUrl":"https:\/\/www.federassantas.org.br\/novosite\/wp-content\/uploads\/2021\/12\/logo.png","width":243,"height":59,"caption":"Federassantas"},"image":{"@id":"https:\/\/www.federassantas.org.br\/novosite\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.federassantas.org.br\/novosite\/#\/schema\/person\/75fed98158349313fe56175f232f513c","name":"admin-federas","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.federassantas.org.br\/novosite\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/2a02d7dda59fe8dc6b7ffd3f652e2efede5ccf0dd89dfdc8137c5517f3de8407?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/2a02d7dda59fe8dc6b7ffd3f652e2efede5ccf0dd89dfdc8137c5517f3de8407?s=96&d=mm&r=g","caption":"admin-federas"},"sameAs":["https:\/\/www.federassantas.org.br\/novosite\/"],"url":"https:\/\/www.federassantas.org.br\/novosite\/author\/admin-federas\/"}]}},"_links":{"self":[{"href":"https:\/\/www.federassantas.org.br\/novosite\/wp-json\/wp\/v2\/posts\/38495","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.federassantas.org.br\/novosite\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.federassantas.org.br\/novosite\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.federassantas.org.br\/novosite\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.federassantas.org.br\/novosite\/wp-json\/wp\/v2\/comments?post=38495"}],"version-history":[{"count":4,"href":"https:\/\/www.federassantas.org.br\/novosite\/wp-json\/wp\/v2\/posts\/38495\/revisions"}],"predecessor-version":[{"id":38502,"href":"https:\/\/www.federassantas.org.br\/novosite\/wp-json\/wp\/v2\/posts\/38495\/revisions\/38502"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.federassantas.org.br\/novosite\/wp-json\/wp\/v2\/media\/38501"}],"wp:attachment":[{"href":"https:\/\/www.federassantas.org.br\/novosite\/wp-json\/wp\/v2\/media?parent=38495"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.federassantas.org.br\/novosite\/wp-json\/wp\/v2\/categories?post=38495"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.federassantas.org.br\/novosite\/wp-json\/wp\/v2\/tags?post=38495"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}